{"id":12163,"date":"2024-01-26T06:14:02","date_gmt":"2024-01-26T06:14:02","guid":{"rendered":"https:\/\/dev.hotelmoov.com\/hotels\/moov-hotel-curitiba\/"},"modified":"2026-07-07T11:53:50","modified_gmt":"2026-07-07T11:53:50","slug":"moov-hotel-curitiba","status":"publish","type":"hotels","link":"https:\/\/hotelmoov.com\/es\/hotels\/moov-hotel-curitiba\/","title":{"rendered":"MOOV HOTEL CURITIBA"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12163\" class=\"elementor elementor-12163 elementor-4662\" data-elementor-post-type=\"hotels\">\n\t\t\t\t<div class=\"elementor-element elementor-element-59bf4cd8 js-hero-gallery e-flex e-con-boxed e-con e-parent\" data-id=\"59bf4cd8\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2a2f3362 e-con-full e-flex e-con e-child\" data-id=\"2a2f3362\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7675f59e elementor-hidden-desktop elementor-hidden-tablet elementor-absolute el-button-back-hotel elementor-widget elementor-widget-button\" data-id=\"7675f59e\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/hotelmoov.com\/es\/destinations\/curitiba\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-left\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-286b70df custom-breadcrumb elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"286b70df\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><a href=\"https:\/\/hotelmoov.com\/destinations\/curitiba\/\">Curitiba<\/a> \/ <span style=\"text-decoration: underline;\"><strong>Moov Hotel Curitiba<\/strong><\/span><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3681a264 e-con-full e-flex e-con e-child\" data-id=\"3681a264\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14c7f35 el-hotel-hero-slider elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"14c7f35\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized):not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"14c7f35\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6IjI1NDA0IiwidXJsIjoiaHR0cHM6XC9cL2hvdGVsbW9vdi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA0XC9EZXNpZ24tc2VtLW5vbWUtMi0xLnBuZyIsInNsaWRlc2hvdyI6IjE0YzdmMzUifQ%3D%3D\" href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/Design-sem-nome-2-1.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/Design-sem-nome-2-1-1024x682.png\" alt=\"Design-sem-nome-2-1.png\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"14c7f35\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6IjI1NDA5IiwidXJsIjoiaHR0cHM6XC9cL2hvdGVsbW9vdi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA0XC8yLU1vb3ZIb3RlbEN1cml0aWJhLndlYnAiLCJzbGlkZXNob3ciOiIxNGM3ZjM1In0%3D\" href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/2-MoovHotelCuritiba.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/2-MoovHotelCuritiba-1024x683.webp\" alt=\"2-MoovHotelCuritiba.webp\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"14c7f35\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6IjI1NDE0IiwidXJsIjoiaHR0cHM6XC9cL2hvdGVsbW9vdi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA0XC8zLU1vb3ZIb3RlbEN1cml0aWJhLndlYnAiLCJzbGlkZXNob3ciOiIxNGM3ZjM1In0%3D\" href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/3-MoovHotelCuritiba.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/3-MoovHotelCuritiba-1024x683.webp\" alt=\"3-MoovHotelCuritiba.webp\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"14c7f35\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6IjI1NDE5IiwidXJsIjoiaHR0cHM6XC9cL2hvdGVsbW9vdi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA0XC80LU1vb3ZIb3RlbEN1cml0aWJhLndlYnAiLCJzbGlkZXNob3ciOiIxNGM3ZjM1In0%3D\" href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/4-MoovHotelCuritiba.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/4-MoovHotelCuritiba-1024x683.webp\" alt=\"4-MoovHotelCuritiba.webp\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"14c7f35\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6IjI1NDI0IiwidXJsIjoiaHR0cHM6XC9cL2hvdGVsbW9vdi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA0XC81LU1vb3ZIb3RlbEN1cml0aWJhLndlYnAiLCJzbGlkZXNob3ciOiIxNGM3ZjM1In0%3D\" href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/5-MoovHotelCuritiba.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/5-MoovHotelCuritiba-1024x683.webp\" alt=\"5-MoovHotelCuritiba.webp\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"14c7f35\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6IjI1NDI5IiwidXJsIjoiaHR0cHM6XC9cL2hvdGVsbW9vdi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA0XC82LU1vb3ZIb3RlbEN1cml0aWJhLndlYnAiLCJzbGlkZXNob3ciOiIxNGM3ZjM1In0%3D\" href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/6-MoovHotelCuritiba.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/6-MoovHotelCuritiba-683x1024.webp\" alt=\"6-MoovHotelCuritiba.webp\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46b44af2 elementor-absolute js-hero-gallery-button elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"46b44af2\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M18 15V5C18 4.20435 17.6839 3.44129 17.1213 2.87868C16.5587 2.31607 15.7956 2 15 2H5C4.20435 2 3.44129 2.31607 2.87868 2.87868C2.31607 3.44129 2 4.20435 2 5V15C2 15.7956 2.31607 16.5587 2.87868 17.1213C3.44129 17.6839 4.20435 18 5 18H15C15.7956 18 16.5587 17.6839 17.1213 17.1213C17.6839 16.5587 18 15.7956 18 15ZM4 5C4 4.73478 4.10536 4.48043 4.29289 4.29289C4.48043 4.10536 4.73478 4 5 4H15C15.2652 4 15.5196 4.10536 15.7071 4.29289C15.8946 4.48043 16 4.73478 16 5V9.36L14.92 8.27C14.44 7.78988 13.7889 7.5201 13.11 7.52C12.4315 7.52228 11.7812 7.79173 11.3 8.27L10.39 9.18L9.58 8.37C9.03194 7.83074 8.29388 7.52851 7.525 7.52851C6.75612 7.52851 6.01806 7.83074 5.47 8.37L4 9.85V5ZM4.12 15.45C4.04289 15.3124 4.00162 15.1577 4 15V12.67L6.88 9.79C6.96456 9.70504 7.06507 9.63762 7.17576 9.59162C7.28645 9.54561 7.40513 9.52193 7.525 9.52193C7.64487 9.52193 7.76356 9.54561 7.87424 9.59162C7.98493 9.63762 8.08544 9.70504 8.17 9.79L9 10.6L4.12 15.45ZM12.72 9.69C12.7693 9.63577 12.8296 9.59259 12.8968 9.56329C12.964 9.53399 13.0367 9.51924 13.11 9.52C13.1833 9.51924 13.256 9.53399 13.3232 9.56329C13.3904 9.59259 13.4507 9.63577 13.5 9.69L16 12.18V15C16 15.2652 15.8946 15.5196 15.7071 15.7071C15.5196 15.8946 15.2652 16 15 16H6.4L12.72 9.69ZM21 6C20.7348 6 20.4804 6.10536 20.2929 6.29289C20.1054 6.48043 20 6.73478 20 7V17C20 17.7956 19.6839 18.5587 19.1213 19.1213C18.5587 19.6839 17.7956 20 17 20H7C6.73478 20 6.48043 20.1054 6.29289 20.2929C6.10536 20.4804 6 20.7348 6 21C6 21.2652 6.10536 21.5196 6.29289 21.7071C6.48043 21.8946 6.73478 22 7 22H17C18.3261 22 19.5979 21.4732 20.5355 20.5355C21.4732 19.5979 22 18.3261 22 17V7C22 6.73478 21.8946 6.48043 21.7071 6.29289C21.5196 6.10536 21.2652 6 21 6Z\" fill=\"#EB4141\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver todos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5411ea4f e-con-full e-flex e-con e-child\" data-id=\"5411ea4f\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6bed5259 e-con-full e-flex e-con e-child\" data-id=\"6bed5259\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d816b1b elementor-widget elementor-widget-heading\" data-id=\"7d816b1b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Moov Hotel Curitiba<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78864a64 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"78864a64\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/hotelmoov.com\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\"><g id=\"Icons\"><path id=\"Vector\" d=\"M12.0006 2.98669C10.9397 1.92582 9.50089 1.32983 8.0006 1.32983C6.50031 1.32983 5.06147 1.92582 4.0006 2.98669C2.93974 4.04755 2.34375 5.4864 2.34375 6.98669C2.34375 8.48698 2.93974 9.92582 4.0006 10.9867L7.51394 14.5067C7.57591 14.5692 7.64965 14.6188 7.73089 14.6526C7.81213 14.6865 7.89926 14.7039 7.98727 14.7039C8.07528 14.7039 8.16242 14.6865 8.24365 14.6526C8.32489 14.6188 8.39863 14.5692 8.4606 14.5067L12.0006 10.9534C13.057 9.8969 13.6505 8.46406 13.6505 6.97002C13.6505 5.47599 13.057 4.04314 12.0006 2.98669ZM11.0473 10L8.0006 13.06L4.95394 10C4.35203 9.39757 3.94225 8.63019 3.7764 7.79488C3.61055 6.95958 3.69606 6.09385 4.02214 5.30714C4.34822 4.52043 4.90022 3.84805 5.60836 3.37501C6.3165 2.90196 7.14899 2.64948 8.0006 2.64948C8.85221 2.64948 9.68471 2.90196 10.3928 3.37501C11.101 3.84805 11.653 4.52043 11.9791 5.30714C12.3051 6.09385 12.3907 6.95958 12.2248 7.79488C12.059 8.63019 11.6492 9.39757 11.0473 10ZM6.0006 4.94002C5.46241 5.47987 5.1602 6.21107 5.1602 6.97336C5.1602 7.73564 5.46241 8.46684 6.0006 9.00669C6.40044 9.40721 6.90966 9.68074 7.46437 9.79296C8.01908 9.90517 8.59457 9.85108 9.11865 9.63746C9.64273 9.42384 10.0921 9.06021 10.4103 8.59219C10.7285 8.12417 10.9014 7.5726 10.9073 7.00669C10.9103 6.62882 10.8375 6.25419 10.6932 5.90495C10.5489 5.5557 10.3361 5.23893 10.0673 4.97336C9.80305 4.70307 9.48799 4.48771 9.14022 4.33967C8.79245 4.19162 8.41883 4.11381 8.04087 4.11071C7.66291 4.10761 7.28807 4.17929 6.93792 4.32161C6.58777 4.46394 6.26922 4.67411 6.0006 4.94002ZM9.12727 8.06002C8.87463 8.31652 8.54074 8.47729 8.18269 8.51486C7.82463 8.55242 7.46465 8.46445 7.16428 8.26597C6.8639 8.0675 6.6418 7.77085 6.53594 7.42674C6.43008 7.08264 6.44704 6.71245 6.58391 6.37946C6.72078 6.04647 6.96907 5.77137 7.28633 5.60118C7.60358 5.43099 7.97011 5.37629 8.32323 5.44643C8.67635 5.51657 8.99414 5.70719 9.22228 5.98571C9.45041 6.26422 9.57471 6.61334 9.57394 6.97336C9.56424 7.38487 9.3916 7.77571 9.09394 8.06002H9.12727Z\" fill=\"#EB4141\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Avenida Sete de Setembro, 5732, Batel, Curitiba, CEP 80240-001, Brasil<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58f4be17 elementor-widget elementor-widget-text-editor\" data-id=\"58f4be17\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Reserve ya su Hotel Moov, en pleno Batel: espacios verdes, lugares hist\u00f3ricos y mucha cultura, Curitiba es realmente una ciudad que no debe perderse.<\/p>\n<p>Un hotel situado en una zona privilegiada, con 123 habitaciones equipadas para proporcionarle el descanso que necesita. Sofisticado, moderno y relajado, el Hotel Moov Curitiba es el lugar perfecto para viajeros de negocios o que deseen disfrutar de la encantadora capital de Paran\u00e1. <\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7709c267 e-con-full e-flex e-con e-child\" data-id=\"7709c267\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5f2b1635 e-con-full e-flex e-con e-child\" data-id=\"5f2b1635\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-420c8f43 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"420c8f43\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"64\" height=\"64\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/Cleaning-1.png\" class=\"attachment-thumbnail size-thumbnail wp-image-8344\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-77ee3154 e-con-full e-flex e-con e-child\" data-id=\"77ee3154\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d1b0bce elementor-widget elementor-widget-heading\" data-id=\"7d1b0bce\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Comodidades<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-787c8e73 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"787c8e73\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M11.9998 15.0009C11.4065 15.0009 10.8264 15.1769 10.3331 15.5065C9.83974 15.8362 9.45522 16.3047 9.22816 16.8529C9.00109 17.4011 8.94168 18.0043 9.05744 18.5862C9.17319 19.1682 9.45892 19.7027 9.87847 20.1223C10.298 20.5418 10.8326 20.8275 11.4145 20.9433C11.9965 21.059 12.5997 20.9996 13.1478 20.7726C13.696 20.5455 14.1646 20.161 14.4942 19.6676C14.8238 19.1743 14.9998 18.5943 14.9998 18.0009C14.9998 17.2053 14.6837 16.4422 14.1211 15.8796C13.5585 15.317 12.7954 15.0009 11.9998 15.0009ZM11.9998 19.0009C11.802 19.0009 11.6087 18.9423 11.4442 18.8324C11.2798 18.7225 11.1516 18.5663 11.0759 18.3836C11.0002 18.2009 10.9804 17.9998 11.019 17.8058C11.0576 17.6119 11.1528 17.4337 11.2927 17.2938C11.4325 17.154 11.6107 17.0587 11.8047 17.0202C11.9987 16.9816 12.1998 17.0014 12.3825 17.0771C12.5652 17.1527 12.7214 17.2809 12.8313 17.4454C12.9411 17.6098 12.9998 17.8032 12.9998 18.0009C12.9998 18.2662 12.8944 18.5205 12.7069 18.708C12.5194 18.8956 12.265 19.0009 11.9998 19.0009ZM11.9998 11.0009C10.1445 11.0073 8.36635 11.7438 7.0498 13.0509C6.86354 13.2383 6.759 13.4918 6.759 13.7559C6.759 14.0201 6.86354 14.2736 7.0498 14.4609C7.23716 14.6472 7.49061 14.7517 7.7548 14.7517C8.01898 14.7517 8.27243 14.6472 8.45979 14.4609C8.92425 13.9953 9.47601 13.6259 10.0835 13.3738C10.6909 13.1217 11.3421 12.992 11.9998 12.992C12.6575 12.992 13.3087 13.1217 13.9161 13.3738C14.5236 13.6259 15.0753 13.9953 15.5398 14.4609C15.7244 14.6494 15.976 14.7572 16.2398 14.7609C16.4427 14.7726 16.6443 14.7222 16.8178 14.6164C16.9914 14.5106 17.1285 14.3544 17.2111 14.1687C17.2936 13.983 17.3176 13.7766 17.2799 13.5769C17.2421 13.3772 17.1444 13.1937 16.9998 13.0509C16.3418 12.3976 15.5616 11.8804 14.7037 11.5286C13.8458 11.1769 12.927 10.9976 11.9998 11.0009ZM11.9998 7.00094C9.08378 7.00869 6.28837 8.16566 4.21979 10.2209C4.12656 10.3142 4.0526 10.4249 4.00214 10.5467C3.95167 10.6685 3.9257 10.7991 3.9257 10.9309C3.9257 11.1972 4.03149 11.4526 4.21979 11.6409C4.4081 11.8292 4.66349 11.935 4.92979 11.935C5.1961 11.935 5.45149 11.8292 5.63979 11.6409C7.3273 9.95553 9.61479 9.00886 11.9998 9.00886C14.3848 9.00886 16.6723 9.95553 18.3598 11.6409C18.4532 11.7336 18.5641 11.8069 18.6859 11.8567C18.8077 11.9065 18.9382 11.9317 19.0698 11.9309C19.2014 11.9317 19.3319 11.9065 19.4537 11.8567C19.5755 11.8069 19.6864 11.7336 19.7798 11.6409C19.8735 11.548 19.9479 11.4374 19.9987 11.3155C20.0495 11.1937 20.0756 11.063 20.0756 10.9309C20.0756 10.7989 20.0495 10.6682 19.9987 10.5464C19.9479 10.4245 19.8735 10.3139 19.7798 10.2209C17.7112 8.16566 14.9158 7.00869 11.9998 7.00094ZM22.6098 7.39094C21.2168 5.99704 19.5628 4.89129 17.7423 4.13687C15.9218 3.38245 13.9704 2.99414 11.9998 2.99414C10.0292 2.99414 8.07783 3.38245 6.25732 4.13687C4.43681 4.89129 2.7828 5.99704 1.38979 7.39094C1.20149 7.57924 1.0957 7.83464 1.0957 8.10094C1.0957 8.36724 1.20149 8.62263 1.38979 8.81094C1.5781 8.99924 1.83349 9.10503 2.09979 9.10503C2.3661 9.10503 2.62149 8.99924 2.80979 8.81094C5.24757 6.37443 8.55315 5.00571 11.9998 5.00571C15.4464 5.00571 18.752 6.37443 21.1898 8.81094C21.2828 8.90467 21.3934 8.97906 21.5152 9.02983C21.6371 9.0806 21.7678 9.10674 21.8998 9.10674C22.0318 9.10674 22.1625 9.0806 22.2844 9.02983C22.4062 8.97906 22.5168 8.90467 22.6098 8.81094C22.7035 8.71798 22.7779 8.60737 22.8287 8.48551C22.8795 8.36366 22.9056 8.23295 22.9056 8.10094C22.9056 7.96893 22.8795 7.83822 22.8287 7.71636C22.7779 7.5945 22.7035 7.4839 22.6098 7.39094Z\" fill=\"#EB4141\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wi-Fi Gratuito<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M20 13.18V12C19.9986 10.5831 19.4958 9.21247 18.5806 8.13077C17.6655 7.04908 16 6.5 13 6.09V6C13 5.73478 12.8946 5.48043 12.7071 5.29289C12.5196 5.10536 12.2652 5 12 5C11.7348 5 11.4804 5.10536 11.2929 5.29289C11.1054 5.48043 11 5.73478 11 6V6.09C8 6.5 6.33452 7.04908 5.41939 8.13077C4.50425 9.21247 4.00144 10.5831 4 12V13.18C3.41645 13.3863 2.911 13.7681 2.55294 14.2729C2.19488 14.7778 2.00174 15.3811 2 16V18C2 18.2652 2.10536 18.5196 2.29289 18.7071C2.48043 18.8946 2.73478 19 3 19C8.088 19 15.0954 19 21 19C21.2652 19 21.5196 18.8946 21.7071 18.7071C21.8946 18.5196 22 18.2652 22 18V16C21.9983 15.3811 21.8051 14.7778 21.4471 14.2729C21.089 13.7681 20.5835 13.3863 20 13.18ZM6 12C6 10.9391 6.42143 9.92172 7.17157 9.17157C7.92172 8.42143 10 8 12 8C14 8 16.0783 8.42143 16.8284 9.17157C17.5786 9.92172 18 10.9391 18 12V13H6V12ZM20 17H4V16C4 15.7348 4.10536 15.4804 4.29289 15.2929C4.48043 15.1054 4.73478 15 5 15H19C19.2652 15 19.5196 15.1054 19.7071 15.2929C19.8946 15.4804 20 15.7348 20 16V17Z\" fill=\"#EB4141\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Recepci\u00f3n 24 horas (check-out expr\u00e9s)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M13 7H10C9.73479 7 9.48043 7.10536 9.2929 7.29289C9.10536 7.48043 9 7.73478 9 8V16C9 16.2652 9.10536 16.5196 9.2929 16.7071C9.48043 16.8946 9.73479 17 10 17C10.2652 17 10.5196 16.8946 10.7071 16.7071C10.8946 16.5196 11 16.2652 11 16V14H13C13.7957 14 14.5587 13.6839 15.1213 13.1213C15.6839 12.5587 16 11.7956 16 11V10C16 9.20435 15.6839 8.44129 15.1213 7.87868C14.5587 7.31607 13.7957 7 13 7ZM14 11C14 11.2652 13.8946 11.5196 13.7071 11.7071C13.5196 11.8946 13.2652 12 13 12H11V9H13C13.2652 9 13.5196 9.10536 13.7071 9.29289C13.8946 9.48043 14 9.73478 14 10V11ZM12 2C10.0222 2 8.08879 2.58649 6.4443 3.6853C4.79981 4.78412 3.51809 6.3459 2.76121 8.17317C2.00433 10.0004 1.8063 12.0111 2.19215 13.9509C2.578 15.8907 3.53041 17.6725 4.92894 19.0711C6.32746 20.4696 8.10929 21.422 10.0491 21.8079C11.9889 22.1937 13.9996 21.9957 15.8268 21.2388C17.6541 20.4819 19.2159 19.2002 20.3147 17.5557C21.4135 15.9112 22 13.9778 22 12C22 10.6868 21.7413 9.38642 21.2388 8.17317C20.7363 6.95991 19.9997 5.85752 19.0711 4.92893C18.1425 4.00035 17.0401 3.26375 15.8268 2.7612C14.6136 2.25866 13.3132 2 12 2ZM12 20C10.4178 20 8.87104 19.5308 7.55544 18.6518C6.23985 17.7727 5.21447 16.5233 4.60897 15.0615C4.00347 13.5997 3.84504 11.9911 4.15372 10.4393C4.4624 8.88743 5.22433 7.46197 6.34315 6.34315C7.46197 5.22433 8.88743 4.4624 10.4393 4.15372C11.9911 3.84504 13.5997 4.00346 15.0615 4.60896C16.5233 5.21447 17.7727 6.23984 18.6518 7.55544C19.5308 8.87103 20 10.4177 20 12C20 14.1217 19.1572 16.1566 17.6569 17.6569C16.1566 19.1571 14.1217 20 12 20Z\" fill=\"#EB4141\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aparcamiento Privado<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M16.0006 7C16.3962 7 16.7828 6.8827 17.1117 6.66294C17.4406 6.44318 17.697 6.13082 17.8484 5.76537C17.9997 5.39992 18.0393 4.99778 17.9622 4.60982C17.885 4.22186 17.6945 3.86549 17.4148 3.58579C17.1351 3.30608 16.7787 3.1156 16.3908 3.03843C16.0028 2.96126 15.6007 3.00087 15.2352 3.15224C14.8698 3.30362 14.5574 3.55996 14.3377 3.88886C14.1179 4.21776 14.0006 4.60444 14.0006 5C14.0006 5.53043 14.2113 6.03914 14.5864 6.41421C14.9615 6.78929 15.4702 7 16.0006 7ZM12.7006 18.4C12.2998 18.9248 11.7753 19.3422 11.1739 19.615C10.5725 19.8878 9.91291 20.0074 9.25402 19.9632C8.59514 19.919 7.95744 19.7124 7.39785 19.3618C6.83826 19.0111 6.37418 18.5274 6.04703 17.9538C5.71988 17.3802 5.53984 16.7345 5.52297 16.0743C5.50611 15.4142 5.65295 14.7601 5.95038 14.1705C6.24782 13.5809 6.6866 13.0742 7.22756 12.6954C7.76852 12.3167 8.39483 12.0778 9.0506 12C9.31582 11.9708 9.55858 11.8375 9.72549 11.6293C9.8924 11.4212 9.96978 11.1552 9.9406 10.89C9.91143 10.6248 9.77809 10.382 9.56993 10.2151C9.36176 10.0482 9.09582 9.97083 8.8306 10C7.2393 10.0888 5.74848 10.8062 4.68608 11.9942C3.62369 13.1823 3.07676 14.7437 3.1656 16.335C3.25445 17.9263 3.9718 19.4171 5.15984 20.4795C6.34789 21.5419 7.9093 22.0888 9.5006 22C10.4321 22 11.3508 21.7831 12.1839 21.3666C13.017 20.95 13.7417 20.3452 14.3006 19.6C14.4597 19.3878 14.5281 19.1211 14.4906 18.8586C14.453 18.596 14.3128 18.3591 14.1006 18.2C13.8884 18.0409 13.6217 17.9725 13.3592 18.0101C13.0966 18.0476 12.8597 18.1878 12.7006 18.4ZM19.5006 20H18.5006V15C18.5006 14.7348 18.3952 14.4804 18.2077 14.2929C18.0202 14.1054 17.7658 14 17.5006 14H12.9306L14.6206 9.34V9.03C14.6255 8.9701 14.6255 8.9099 14.6206 8.85C14.6263 8.7868 14.6263 8.72321 14.6206 8.66C14.5945 8.60134 14.5645 8.54454 14.5306 8.49C14.5006 8.43545 14.4636 8.38503 14.4206 8.34C14.3777 8.28913 14.3271 8.24527 14.2706 8.21C14.2706 8.21 14.2706 8.15 14.1906 8.13L9.7106 5.55H9.5906C9.52929 5.52408 9.46568 5.50399 9.4006 5.49H9.0006C8.93113 5.50436 8.86387 5.5279 8.8006 5.56H8.6906L6.0006 7.13C5.80942 7.23831 5.65923 7.40657 5.57325 7.60877C5.48727 7.81098 5.47028 8.03588 5.52491 8.24871C5.57954 8.46154 5.70275 8.65045 5.87549 8.78625C6.04823 8.92204 6.26089 8.99717 6.4806 9C6.66254 9.00479 6.84233 8.95985 7.0006 8.87L9.2306 7.57L12.4706 9.45L10.5806 14.66C10.5757 14.7132 10.5757 14.7668 10.5806 14.82C10.5712 14.8796 10.5712 14.9404 10.5806 15C10.599 15.1283 10.6258 15.2552 10.6606 15.38L10.7706 15.53C10.7978 15.5892 10.8351 15.6434 10.8806 15.69C10.9233 15.7257 10.9704 15.7559 11.0206 15.78C11.0801 15.8258 11.1437 15.8659 11.2106 15.9C11.3196 15.9396 11.4346 15.9599 11.5506 15.96H16.5506V20.96C16.5506 21.2252 16.656 21.4796 16.8435 21.6671C17.031 21.8546 17.2854 21.96 17.5506 21.96H19.5506C19.8158 21.96 20.0702 21.8546 20.2577 21.6671C20.4452 21.4796 20.5506 21.2252 20.5506 20.96C20.5506 20.6948 20.4452 20.4404 20.2577 20.2529C20.0702 20.0654 19.8158 19.96 19.5506 19.96L19.5006 20Z\" fill=\"#EB4141\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Accesible para Personas con Movilidad Reducida<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M12 8C12.2652 8.00018 12.5194 8.10559 12.7069 8.29309C12.8944 8.48059 12.9998 8.73484 13 9C13 9.26522 13.1054 9.51957 13.2929 9.70711C13.4804 9.89464 13.7348 10 14 10C14.2652 10 14.5196 9.89464 14.7071 9.70711C14.8946 9.51957 15 9.26522 15 9C14.9997 8.50078 14.8749 8.00952 14.6367 7.57077C14.3986 7.13201 14.0547 6.75963 13.6362 6.48739C13.2178 6.21514 12.738 6.05165 12.2404 6.01172C11.7428 5.97179 11.2431 6.0567 10.7866 6.25874C10.33 6.46079 9.93119 6.77357 9.62614 7.16875C9.32109 7.56392 9.11949 8.02899 9.03963 8.52178C8.95977 9.01456 9.00417 9.51949 9.1688 9.99078C9.33343 10.4621 9.61309 10.8848 9.98242 11.2207C9.99242 11.2298 10.1436 11.3906 10.1758 11.4355C10.289 11.6002 10.3496 11.7953 10.3496 11.9951C10.3496 12.1949 10.289 12.3901 10.1758 12.5547C10.1015 12.6629 10.0493 12.7847 10.0221 12.9131C9.99496 13.0416 9.99334 13.1741 10.0174 13.3031C10.0414 13.4322 10.0906 13.5552 10.1622 13.6652C10.2338 13.7752 10.3263 13.8701 10.4346 13.9443C10.5428 14.0186 10.6646 14.0708 10.793 14.098C10.9214 14.1252 11.054 14.1268 11.183 14.1028C11.312 14.0787 11.4351 14.0295 11.5451 13.9579C11.6551 13.8863 11.75 13.7938 11.8242 13.6855C12.1672 13.1869 12.3505 12.5957 12.3496 11.9905C12.3487 11.3852 12.1638 10.7945 11.8193 10.2969C11.6654 10.1029 11.5014 9.91712 11.3281 9.74023C11.2686 9.68592 11.2155 9.62498 11.1699 9.55859C11.0688 9.40803 11.0105 9.23283 11.0013 9.05171C10.9921 8.8706 11.0322 8.69037 11.1175 8.53031C11.2027 8.37024 11.3298 8.23635 11.4853 8.14294C11.6407 8.04954 11.8186 8.00013 12 8ZM12 2C10.9263 2.00009 9.86707 2.24714 8.90414 2.72204C7.9412 3.19694 7.10041 3.88696 6.44677 4.73874C5.79314 5.59053 5.34419 6.58124 5.13463 7.63426C4.92508 8.68728 4.96054 9.77439 5.23828 10.8115C5.30772 11.0668 5.47548 11.2841 5.70481 11.4159C5.93414 11.5477 6.20636 11.5833 6.46186 11.5148C6.71737 11.4464 6.93533 11.2795 7.06804 11.0507C7.20075 10.8218 7.23738 10.5498 7.16992 10.294C6.98576 9.60651 6.9505 8.88763 7.06648 8.18542C7.18245 7.4832 7.44701 6.81384 7.84245 6.22208C8.23789 5.63032 8.7551 5.1298 9.35951 4.75398C9.96393 4.37815 10.6416 4.1357 11.3472 4.04281C12.0529 3.94992 12.7702 4.00874 13.4513 4.21535C14.1324 4.42195 14.7615 4.77157 15.2966 5.24084C15.8317 5.7101 16.2605 6.2882 16.5542 6.93648C16.848 7.58475 17 8.28827 17 9C16.9958 9.90303 16.7525 10.7888 16.2949 11.5674L12.7315 19C12.5556 19.3036 12.3031 19.5558 11.9993 19.7313C11.6955 19.9068 11.3509 19.9994 11 20C10.4717 19.993 9.96709 19.7801 9.59352 19.4065C9.21995 19.0329 9.00699 18.5283 9 18C8.99999 17.6492 9.09263 17.3045 9.26855 17.001C9.40142 16.7713 9.43759 16.4982 9.3691 16.2418C9.30061 15.9854 9.13307 15.7667 8.90334 15.6338C8.67361 15.5009 8.4005 15.4647 8.1441 15.5332C7.8877 15.6017 7.669 15.7693 7.53613 15.999C7.27151 16.4565 7.10022 16.962 7.03215 17.4861C6.96409 18.0102 7.00061 18.5427 7.13959 19.0526C7.27858 19.5625 7.51728 20.0399 7.84189 20.457C8.1665 20.8741 8.57058 21.2227 9.03076 21.4827C9.49094 21.7427 9.99809 21.9088 10.5229 21.9716C11.0477 22.0343 11.5797 21.9924 12.0882 21.8483C12.5967 21.7041 13.0716 21.4606 13.4854 21.1318C13.8992 20.803 14.2437 20.3954 14.499 19.9326L18.0625 12.5C18.6768 11.4358 19.0001 10.2287 19 8.99998C18.9999 7.77125 18.6764 6.56418 18.062 5.50008C17.4476 4.43598 16.564 3.55234 15.4999 2.93795C14.4358 2.32356 13.2287 2.00008 12 2Z\" fill=\"#EB4141\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Insonorizaci\u00f3n<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M20.8994 10.12C20.8494 9.87 20.7794 9.63 20.7094 9.39C20.2818 8.00973 19.525 6.75416 18.5041 5.73154C17.4832 4.70892 16.2289 3.94992 14.8494 3.52C14.2027 3.31847 13.269 3.06 13.1194 3.05V3C13.1194 2.73478 13.014 2.48043 12.8265 2.29289C12.6389 2.10536 12.3846 2 12.1194 2C11.8542 2 11.5998 2.10536 11.4123 2.29289C11.2247 2.48043 11.1194 2.73478 11.1194 3V3.06C10.5469 3.12883 9.86176 3.24244 9.36938 3.4C9.11938 3.48 8.88937 3.57 8.64937 3.66C7.41457 4.14891 6.30437 4.90708 5.39962 5.8793C4.49488 6.85151 3.81837 8.01328 3.41938 9.28C3.16528 10.0867 3.10938 10.5561 3.10938 11.24C3.10938 11.49 3.10938 11.74 3.10938 12C3.10938 12.2652 3.21473 12.5196 3.40227 12.7071C3.5898 12.8946 3.84416 13 4.10938 13H11.1094C11.1094 23.489 13.1094 21.0773 13.1094 13H20.1094C20.3746 13 20.6289 12.8946 20.8165 12.7071C21.004 12.5196 21.1094 12.2652 21.1094 12C21.1094 11.3786 20.9995 10.5 20.8994 10.12ZM7.99938 11H5.07938C5.07938 11 5.07938 10.93 5.07938 10.89C5.07938 10.4892 5.11983 10.2104 5.28938 9.73C5.60942 8.82311 6.1129 7.99189 6.76842 7.2882C7.42393 6.58452 8.21742 6.02345 9.09938 5.64C8.42938 7.35076 8.05733 9.16363 7.99938 11ZM9.99938 11C10.1894 7.09 11.4394 5 11.9994 5C12.5594 5 13.7894 7.09 13.9994 11H9.99938ZM15.9994 11C15.9414 9.16363 15.5694 7.35076 14.8994 5.64C15.7695 6.03569 16.5493 6.60538 17.1908 7.31396C17.8323 8.02254 18.3219 8.85499 18.6294 9.76C18.7606 10.1361 18.8594 10.5811 18.8594 10.98L15.9994 11Z\" fill=\"#EB4141\"><\/path><path d=\"M11.4071 21.7211C11.2102 21.5425 11.0996 21.3002 11.0996 21.0476V12L13.1996 12.0763V14.3048V21.0476C13.1996 21.3002 13.089 21.5425 12.8921 21.7211C12.6952 21.8997 12.4281 22 12.1496 22C11.8711 22 11.6041 21.8997 11.4071 21.7211Z\" fill=\"#EB4141\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Patio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dog\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Admite mascotas (cargo adicional)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-726d75cc el-scroll-nav e-flex e-con-boxed e-con e-parent\" data-id=\"726d75cc\" data-element_type=\"container\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:80,&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky_offset_mobile&quot;:48,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d8574ea elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"7d8574ea\" data-element_type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;},&quot;layout&quot;:&quot;horizontal&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/hotelmoov.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-nav-menu.min.css\">\t\t\t<nav class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-7d8574ea\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-17134\"><a href=\"#quartos\" class=\"elementor-item elementor-item-anchor\">Habitaciones<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-17135\"><a href=\"#hotel\" class=\"elementor-item elementor-item-anchor\">Hotel<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-17136\"><a href=\"#location\" class=\"elementor-item elementor-item-anchor\">Ubicaci\u00f3n<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-17137\"><a href=\"#reviews\" class=\"elementor-item elementor-item-anchor\">Rese\u00f1as<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-7d8574ea\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-17134\"><a href=\"#quartos\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Habitaciones<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-17135\"><a href=\"#hotel\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Hotel<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-17136\"><a href=\"#location\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Ubicaci\u00f3n<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-17137\"><a href=\"#reviews\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Rese\u00f1as<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f2a3b0 e-flex e-con-boxed e-con e-parent\" data-id=\"8f2a3b0\" data-element_type=\"container\" id=\"quartos\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-280ec290 e-con-full e-flex e-con e-child\" data-id=\"280ec290\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90b4854 elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"90b4854\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Habitaciones<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fc89b1 el-hotel-form-booking elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-theme_booking_form\" data-id=\"5fc89b1\" data-element_type=\"widget\" data-widget_type=\"theme_booking_form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"form-booking js-form-booking\" data-api=\"omni\">\n\t\t<button type=\"button\" class=\"js-show-search form__close-btn\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/themes\/hello-elementor-child\/img\/ico-close.svg\" alt=\"\">\n\t\t<\/button>\n\n\t\t<form action=\"https:\/\/book.omnibees.com\/hotelresults\" id=\"hotel-page-hotel-page-booking-form\" method=\"GET\" class=\"js-form-booking-form\">\n\t\t\t<div class=\"form__body\">\n\t\t\t\t<div class=\"form__toggle form__toggle-location\">\n\t\t\t\t\t<div class=\"form__toggle-inner\">\n\t\t\t\t\t\t<label for=\"hotel-page-field-location\" class=\"form__label\">D\u00f3nde<\/label>\n\n\t\t\t\t\t\t<div class=\"form__controls\">\n\t\t\t\t\t\t\t<input type=\"text\" class=\"field js-input-location js-location-fill\" name=\"q\" id=\"hotel-page-field-location\" value=\"\" placeholder=\"Buscar destinos\" autocomplete=\"off\" readonly>\n\t\t\t\t\t\t<\/div><!-- \/.form__controls -->\n\t\t\t\t\t<\/div><!-- \/.form__toggle-inner -->\n\n\t\t\t\t\t<div class=\"form__toggle-dropdown js-location-select\">\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\tPortugal\t\t\t\t\t\t<\/p>\n\n\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" data-id=\"100379266\" data-value=\"Porto Centro\" data-api=\"mirai\">Porto Centro<\/a>\n\t\t\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" data-id=\"100379267\" data-value=\"Porto Norte\" data-api=\"mirai\">Porto Norte<\/a>\n\t\t\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" data-id=\"100379268\" data-value=\"Oeiras\" data-api=\"mirai\">Oeiras<\/a>\n\t\t\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" data-id=\"100379269\" data-value=\"Lisboa Oriente\" data-api=\"mirai\">Lisboa Oriente<\/a>\n\t\t\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" data-id=\"100379270\" data-value=\"\u00c9vora\" data-api=\"mirai\">\u00c9vora<\/a>\n\t\t\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" data-id=\"100380045\" data-value=\"Boavista\" data-api=\"mirai\">Boavista<\/a>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" data-id=\"518696234\" data-value=\"Matosinhos Sul\" data-api=\"mirai\">Matosinhos Sul<\/a>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\tBRASIL\t\t\t\t\t\t<\/p>\n\n\t\t\t\t\t\t<ul>\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" data-id=\"9291\" data-value=\"Curitiba\" data-api=\"omni\">Curitiba<\/a>\n\t\t\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" data-id=\"13690\" data-value=\"Porto Alegre\" data-api=\"omni\">Porto Alegre<\/a>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" data-id=\"23202\" data-value=\"S\u00e3o Paulo\" data-api=\"omni\">S\u00e3o Paulo<\/a>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div><!-- \/.form__toggle-dropdown -->\n\t\t\t\t<\/div><!-- \/.form__toggle -->\n\n\t\t\t\t<div class=\"form__toggle js-flatpickr-container\">\n\t\t\t\t\t<label for=\"hotel-page-field-full-date\" class=\"hidden-desktop form__label\">Seleccione las fechas<\/label>\n\n\t\t\t\t\t<div class=\"form__toggle-inner form__toggle-inner--flex\">\n\t\t\t\t\t\t<input type=\"text\" class=\"field-full js-flatpickr\" name=\"\" id=\"hotel-page-field-full-date\" value=\"\" placeholder=\"full-date\" autocomplete=\"off\">\n\n\t\t\t\t\t\t<div class=\"form__toggle-col\">\n\t\t\t\t\t\t\t<label for=\"hotel-page-field-checkin\" class=\"form__label\">Check-In<\/label>\n\n\t\t\t\t\t\t\t<div class=\"form__controls\">\n\t\t\t\t\t\t\t\t<input type=\"text\" class=\"field js-checkin\" name=\"CheckIn\" id=\"hotel-page-field-checkin\" value=\"\" placeholder=\"Fecha\" autocomplete=\"off\">\n\t\t\t\t\t\t\t<\/div><!-- \/.form__controls -->\n\t\t\t\t\t\t<\/div><!-- \/.form__toggle-col -->\n\n\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/themes\/hello-elementor-child\/img\/ico-chevron-check-in-out.svg\" alt=\"\">\n\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t<div class=\"form__toggle-col\">\n\t\t\t\t\t\t\t<label for=\"hotel-page-field-checkout\" class=\"form__label\">Check-Out<\/label>\n\n\t\t\t\t\t\t\t<div class=\"form__controls\">\n\t\t\t\t\t\t\t\t<input type=\"text\" class=\"field js-checkout\" name=\"CheckOut\" id=\"hotel-page-field-checkout\" value=\"\" placeholder=\"Fecha\" autocomplete=\"off\">\n\t\t\t\t\t\t\t<\/div><!-- \/.form__controls -->\n\t\t\t\t\t\t<\/div><!-- \/.form__toggle-col -->\n\t\t\t\t\t<\/div><!-- \/.form__toggle-inner -->\n\t\t\t\t<\/div><!-- \/.form__toggle -->\n\n\t\t\t\t<div class=\"form__toggle form__toggle--buttons\">\n\t\t\t\t\t<div class=\"form__toggle-inner form__toggle-inner--button\">\n\t\t\t\t\t\t<div class=\"form__toggle-entry\">\n\t\t\t\t\t\t\t<label for=\"hotel-page-field-guests\" class=\"form__label\">Qui\u00e9n<\/label>\n\n\t\t\t\t\t\t\t<div class=\"form__controls\">\n\t\t\t\t\t\t\t\t<input type=\"text\" class=\"field js-input-people\" name=\"\" id=\"hotel-page-field-guests\" value=\"\" readonly placeholder=\"A\u00f1adir invitados\" autocomplete=\"off\">\n\t\t\t\t\t\t\t<\/div><!-- \/.form__controls -->\n\n\t\t\t\t\t\t\t<div class=\"form__toggle-entry-dropdown\">\n                                <div class=\"inner-scroll\">\n\n                                <div class=\"form__row\">\n                                    <label for=\"hotel-page-field-rooms\" class=\"form__label\">N\u00ba de Quartos<\/label>\n\n                                    <div class=\"form__number\">\n                                        <button type=\"button\" class=\"field-rooms-decrement\">\n                                            <img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/themes\/hello-elementor-child\/img\/ico-minus.svg\" alt=\"\">\n                                        <\/button>\n\n                                        <input type=\"number\" class=\"field js-field-rooms\" name=\"rooms\" id=\"hotel-page-field-rooms\" value=\"1\" autocomplete=\"off\" readonly>\n\n                                        <button type=\"button\" class=\"field-rooms-increment\">\n                                            <img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/themes\/hello-elementor-child\/img\/ico-plus.svg\" alt=\"\">\n                                        <\/button>\n                                    <\/div><!-- \/.form__number -->\n                                <\/div><!-- \/.form__row -->\n\n                                <div class=\"room-number-data\" data-api=\"1\">\n                                    <label class=\"room-number form__label\">Quarto 1<\/label>\n                                    <div class=\"form__row\">\n                                        <label for=\"hotel-page-field-adults\" class=\"form__label\">Adultos<\/label>\n\n                                        <div class=\"form__number\">\n                                            <button type=\"button\" class=\"decrement\">\n                                                <img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/themes\/hello-elementor-child\/img\/ico-minus.svg\" alt=\"\">\n                                            <\/button>\n\n                                            <input type=\"number\" class=\"field js-field-adults\" name=\"ad\" id=\"hotel-page-field-adults\" value=\"0\" autocomplete=\"off\">\n\n                                            <button type=\"button\" class=\"increment\">\n                                                <img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/themes\/hello-elementor-child\/img\/ico-plus.svg\" alt=\"\">\n                                            <\/button>\n                                        <\/div><!-- \/.form__number -->\n                                    <\/div><!-- \/.form__row -->\n\n                                    <div class=\"form__row\">\n                                        <label for=\"hotel-page-field-children\" class=\"form__label\">\n\t\t\t                                Ni\u00f1os                                            <span> 0 a 12 A\u00f1os<\/span>\n                                        <\/label>\n\n                                        <div class=\"form__number\">\n                                            <button type=\"button\" class=\"decrement\">\n                                                <img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/themes\/hello-elementor-child\/img\/ico-minus.svg\" alt=\"\">\n                                            <\/button>\n\n                                            <input type=\"number\" class=\"field js-field-children\" name=\"ch\" id=\"hotel-page-field-children\" value=\"0\" autocomplete=\"off\">\n\n                                            <button type=\"button\" class=\"increment\">\n                                                <img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/themes\/hello-elementor-child\/img\/ico-plus.svg\" alt=\"\">\n                                            <\/button>\n                                        <\/div><!-- \/.form__number -->\n                                    <\/div><!-- \/.form__row -->\n\n                                    <div class=\"form__children\"><\/div><!-- \/.form__children -->\n                                <\/div>\n\n                                <\/div>\n\t\t\t\t\t\t\t<\/div><!-- \/.form__toggle-entry-dropdown -->\n\t\t\t\t\t\t<\/div><!-- \/.form__toggle-entry -->\n\n\t\t\t\t\t\t<div class=\"form__promo\">\n\t\t\t\t\t\t\t<button type=\"button\" class=\"form__btn js-show-promo\">\n\t\t\t\t\t\t\t\t<svg width=\"14\" height=\"14\" viewBox=\"0 0 14 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t\t\t<path d=\"M4.37631 3.49936C4.20325 3.49936 4.03408 3.55068 3.89019 3.64682C3.74629 3.74297 3.63414 3.87963 3.56792 4.03951C3.50169 4.1994 3.48436 4.37533 3.51812 4.54506C3.55189 4.7148 3.63522 4.87071 3.75759 4.99308C3.87996 5.11545 4.03587 5.19878 4.20561 5.23255C4.37534 5.26631 4.55127 5.24898 4.71116 5.18275C4.87105 5.11653 5.0077 5.00438 5.10385 4.86048C5.19999 4.71659 5.25131 4.54742 5.25131 4.37436C5.25131 4.14229 5.15912 3.91973 4.99503 3.75564C4.83094 3.59155 4.60838 3.49936 4.37631 3.49936ZM12.3213 6.24686L7.41548 1.33519C7.36097 1.28113 7.29633 1.23835 7.22526 1.20933C7.15419 1.1803 7.07808 1.16558 7.00131 1.16603H1.75131C1.5966 1.16603 1.44823 1.22748 1.33883 1.33688C1.22944 1.44628 1.16798 1.59465 1.16798 1.74936V6.99936C1.16753 7.07613 1.18225 7.15223 1.21128 7.2233C1.24031 7.29438 1.28308 7.35902 1.33715 7.41353L6.24881 12.3194C6.57694 12.6471 7.02173 12.8312 7.48548 12.8312C7.94923 12.8312 8.39402 12.6471 8.72215 12.3194L12.3213 8.74936C12.649 8.42123 12.8331 7.97644 12.8331 7.51269C12.8331 7.04894 12.649 6.60415 12.3213 6.27603V6.24686ZM11.4988 7.89186L7.89381 11.491C7.78452 11.5997 7.63667 11.6607 7.48256 11.6607C7.32845 11.6607 7.18061 11.5997 7.07131 11.491L2.33465 6.76019V2.33269H6.76215L11.4988 7.06936C11.5529 7.12387 11.5956 7.18851 11.6247 7.25958C11.6537 7.33065 11.6684 7.40675 11.668 7.48353C11.6673 7.63656 11.6066 7.78321 11.4988 7.89186Z\" fill=\"currentColor\"\/>\n\t\t\t\t\t\t\t\t<\/svg>\n\n\t\t\t\t\t\t\t\tPromo Code\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t\t<div class=\"form__promo-dropdown\">\n\t\t\t\t\t\t\t\t<label for=\"hotel-page-field-promo-code\" class=\"form__promo-label\">A\u00f1adir un Promo Code<\/label>\n\n\t\t\t\t\t\t\t\t<input type=\"text\" class=\"field__promo js-promo-code\" name=\"Code\" id=\"hotel-page-field-promo-code\" value=\"\" placeholder=\"Promo Code\">\n\t\t\t\t\t\t\t<\/div><!-- \/.form__promo-dropdown -->\n\t\t\t\t\t\t<\/div><!-- \/.form__promo -->\n\n\t\t\t\t\t\t<input type=\"hidden\" name=\"c\" value=\"hotelresults\">\n\n\t\t\t\t\t\t<button type=\"submit\" class=\"form__btn form__btn--solid\">\n\t\t\t\t\t\t\t<svg width=\"14\" height=\"14\" viewBox=\"0 0 14 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t\t\t<path d=\"M12.6659 11.8357L10.5018 9.68899C11.3418 8.64156 11.7487 7.31208 11.6386 5.97391C11.5285 4.63575 10.9099 3.39061 9.91 2.49453C8.91007 1.59845 7.60483 1.11954 6.26265 1.15626C4.92046 1.19299 3.64336 1.74257 2.69394 2.69199C1.74452 3.64141 1.19494 4.91851 1.15822 6.26069C1.12149 7.60288 1.6004 8.90812 2.49648 9.90804C3.39257 10.908 4.6377 11.5266 5.97587 11.6366C7.31403 11.7467 8.64352 11.3399 9.69094 10.4998L11.8376 12.6465C11.8918 12.7012 11.9564 12.7446 12.0274 12.7742C12.0985 12.8038 12.1748 12.819 12.2518 12.819C12.3288 12.819 12.405 12.8038 12.4761 12.7742C12.5472 12.7446 12.6117 12.7012 12.6659 12.6465C12.7711 12.5377 12.8299 12.3924 12.8299 12.2411C12.8299 12.0898 12.7711 11.9444 12.6659 11.8357ZM6.41844 10.4998C5.61084 10.4998 4.82136 10.2603 4.14986 9.81166C3.47836 9.36298 2.95499 8.72525 2.64593 7.97911C2.33688 7.23298 2.25601 6.41196 2.41357 5.61987C2.57113 4.82778 2.96003 4.1002 3.53109 3.52914C4.10215 2.95807 4.82973 2.56917 5.62182 2.41162C6.41391 2.25406 7.23494 2.33492 7.98107 2.64398C8.7272 2.95304 9.36493 3.47641 9.81361 4.14791C10.2623 4.81941 10.5018 5.60888 10.5018 6.41649C10.5018 7.49946 10.0716 8.53807 9.30579 9.30384C8.54002 10.0696 7.50141 10.4998 6.41844 10.4998Z\" fill=\"currentColor\"\/>\n\t\t\t\t\t\t\t\t<\/svg>\n\n\t\t\t\t\t\t\t<span>Buscar<\/span>\n\t\t\t\t\t\t<\/button>\n\t\t\t\t\t<\/div><!-- \/.form__toggle-inner -->\n\t\t\t\t<\/div><!-- \/.form__toggle -->\n\t\t\t<\/div><!-- \/.form__body -->\n\t\t<\/form>\n\n\t\t<form action=\"https:\/\/book.omnibees.com\/hotelresults\" class=\"booking-omni\" method=\"GET\" target=\"_blank\">\n\t\t\t<input type=\"hidden\" class=\"hotel\" name=\"q\" value=\"9291\">\n\t\t\t<input type=\"hidden\" class=\"check-in\" name=\"CheckIn\" value=\"\">\n\t\t\t<input type=\"hidden\" class=\"check-out\" name=\"CheckOut\" value=\"\">\n\t\t\t<input type=\"hidden\" class=\"adults\" name=\"ad\" value=\"\">\n\t\t\t<input type=\"hidden\" class=\"children\" name=\"ch\" value=\"\">\n\t\t\t<input type=\"hidden\" class=\"children-ages\" name=\"ag\" value=\"\">\n\t\t\t<input type=\"hidden\" class=\"code\" name=\"code\" value=\"\">\n\t\t\t<input type=\"hidden\" class=\"lang\" name=\"lang\" value=\"es\">\n            <input type=\"hidden\" class=\"nrooms\" name=\"NRooms\" value=\"1\">\n        <\/form>\n\n\t\t<form action=\"https:\/\/reservation.mirai.com\/XMAS\/reservation\/miraiFrontDispatcher.htm\" class=\"booking-mirai\" method=\"GET\" target=\"_blank\">\n\t\t\t<input type=\"hidden\" name=\"clientCodeStrictSearch\" value=\"true\">\n\t\t\t<input type=\"hidden\" name=\"lang\" value=\"es\">\n\t\t\t<input type=\"hidden\" name=\"home\" value=\"https:\/\/hotelmoov.com\/es\/\">\n\t\t\t<input type=\"hidden\" name=\"deviceType\" value=\"DESKTOP_TABLET\">\n\t\t\t<input type=\"hidden\" name=\"step\" value=\"1\">\n\t\t\t<input type=\"hidden\" name=\"currency\" value=\"EUR\">\n\t\t\t<input type=\"hidden\" name=\"hsri\" value=\"02080\">\n\t\t\t<input type=\"hidden\" name=\"idchain\" value=\"502103\">\n\t\t\t<input type=\"hidden\" name=\"idhotel\" value=\"100380045\">\n\t\t\t<input type=\"hidden\" name=\"url\" value=\"true\">\n\n\t\t\t<input type=\"hidden\" class=\"hotel\" name=\"idtokenprovider\" value=\"9291\">\n\t\t\t<input type=\"hidden\" class=\"hotel\" name=\"chainSelectorValue\" value=\"\">\n\t\t\t<input type=\"hidden\" class=\"check-in\" name=\"checkin\" value=\"\">\n\t\t\t<input type=\"hidden\" class=\"nights\" name=\"nights\" value=\"\">\n\t\t\t<input type=\"hidden\" class=\"code\" name=\"clientCode\" value=\"\">\n\t\t\t<input type=\"hidden\" class=\"parties\" name=\"parties\" value=\"W3siYWR1bHRzIjoxLCJjaGlsZHJlbiI6W119XQ==\">\n\t\t<\/form>\n\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-47a739a2 e-con-full e-flex e-con e-child\" data-id=\"47a739a2\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ed9ef42 e-con-full el-room e-flex e-con e-child\" data-id=\"ed9ef42\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-942d0a1 elementor-widget__width-initial el-room__slider elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"942d0a1\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/1-Quarto-Casal-Standard-768x512.webp\" alt=\"1-Quarto-Casal-Standard.webp\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/2-Quarto-Casal-Standard-768x512.webp\" alt=\"2-Quarto-Casal-Standard.webp\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/3-Quarto-Casal-Standard-768x1152.webp\" alt=\"3-Quarto-Casal-Standard.webp\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/4-Quarto-Casal-Standard-768x512.webp\" alt=\"4-Quarto-Casal-Standard.webp\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a0fd489 e-con-full el-room__content e-flex e-con e-child\" data-id=\"7a0fd489\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7b4eed7a e-con-full e-flex e-con e-child\" data-id=\"7b4eed7a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51084967 elementor-widget elementor-widget-heading\" data-id=\"51084967\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Habitaci\u00f3n Doble Est\u00e1ndar<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57b2a10b elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"57b2a10b\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M20 3.5H4C3.20435 3.5 2.44129 3.81607 1.87868 4.37868C1.31607 4.94129 1 5.70435 1 6.5V19.5C1 19.7652 1.10536 20.0196 1.29289 20.2071C1.48043 20.3946 1.73478 20.5 2 20.5H6C6.16471 20.4991 6.32665 20.4576 6.47145 20.3791C6.61625 20.3006 6.73941 20.1876 6.83 20.05L8.54 17.5H15.46L17.17 20.05C17.2606 20.1876 17.3838 20.3006 17.5285 20.3791C17.6733 20.4576 17.8353 20.4991 18 20.5H22C22.2652 20.5 22.5196 20.3946 22.7071 20.2071C22.8946 20.0196 23 19.7652 23 19.5V6.5C23 5.70435 22.6839 4.94129 22.1213 4.37868C21.5587 3.81607 20.7956 3.5 20 3.5ZM21 18.5H18.54L16.83 16C16.7454 15.8531 16.6248 15.7302 16.4796 15.6428C16.3344 15.5553 16.1694 15.5062 16 15.5H8C7.83529 15.5009 7.67335 15.5424 7.52855 15.6209C7.38375 15.6994 7.26059 15.8124 7.17 15.95L5.46 18.5H3V13.5H21V18.5ZM7 11.5V10.5C7 10.2348 7.10536 9.98043 7.29289 9.79289C7.48043 9.60536 7.73478 9.5 8 9.5H10C10.2652 9.5 10.5196 9.60536 10.7071 9.79289C10.8946 9.98043 11 10.2348 11 10.5V11.5H7ZM13 11.5V10.5C13 10.2348 13.1054 9.98043 13.2929 9.79289C13.4804 9.60536 13.7348 9.5 14 9.5H16C16.2652 9.5 16.5196 9.60536 16.7071 9.79289C16.8946 9.98043 17 10.2348 17 10.5V11.5H13ZM21 11.5H19V10.5C19 9.70435 18.6839 8.94129 18.1213 8.37868C17.5587 7.81607 16.7956 7.5 16 7.5H14C13.2599 7.50441 12.5476 7.78221 12 8.28C11.4524 7.78221 10.7401 7.50441 10 7.5H8C7.20435 7.5 6.44129 7.81607 5.87868 8.37868C5.31607 8.94129 5 9.70435 5 10.5V11.5H3V6.5C3 6.23478 3.10536 5.98043 3.29289 5.79289C3.48043 5.60536 3.73478 5.5 4 5.5H20C20.2652 5.5 20.5196 5.60536 20.7071 5.79289C20.8946 5.98043 21 6.23478 21 6.5V11.5Z\" fill=\"#EB4141\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1 Cama doble<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"44\" height=\"34\" viewBox=\"0 0 44 34\" fill=\"none\"><path d=\"M22.6 17.44C23.6672 16.5163 24.5231 15.3738 25.1097 14.09C25.6964 12.8063 26 11.4114 26 10C26 7.34784 24.9464 4.8043 23.0711 2.92893C21.1957 1.05357 18.6522 3.57822e-07 16 3.57822e-07C13.3478 3.57822e-07 10.8043 1.05357 8.92893 2.92893C7.05357 4.8043 6 7.34784 6 10C5.99998 11.4114 6.3036 12.8063 6.89025 14.09C7.4769 15.3738 8.33284 16.5163 9.4 17.44C6.60028 18.7078 4.22493 20.7551 2.55796 23.3371C0.89099 25.9191 0.00294371 28.9266 0 32C0 32.5304 0.210714 33.0391 0.585786 33.4142C0.960859 33.7893 1.46957 34 2 34C2.53043 34 3.03914 33.7893 3.41421 33.4142C3.78929 33.0391 4 32.5304 4 32C4 28.8174 5.26428 25.7652 7.51472 23.5147C9.76516 21.2643 12.8174 20 16 20C19.1826 20 22.2348 21.2643 24.4853 23.5147C26.7357 25.7652 28 28.8174 28 32C28 32.5304 28.2107 33.0391 28.5858 33.4142C28.9609 33.7893 29.4696 34 30 34C30.5304 34 31.0391 33.7893 31.4142 33.4142C31.7893 33.0391 32 32.5304 32 32C31.9971 28.9266 31.109 25.9191 29.442 23.3371C27.7751 20.7551 25.3997 18.7078 22.6 17.44ZM16 16C14.8133 16 13.6533 15.6481 12.6666 14.9888C11.6799 14.3295 10.9108 13.3925 10.4567 12.2961C10.0026 11.1997 9.88378 9.99334 10.1153 8.82946C10.3468 7.66557 10.9182 6.59648 11.7574 5.75736C12.5965 4.91824 13.6656 4.3468 14.8295 4.11529C15.9933 3.88378 17.1997 4.0026 18.2961 4.45672C19.3925 4.91085 20.3295 5.67988 20.9888 6.66658C21.6481 7.65327 22 8.81331 22 10C22 11.5913 21.3679 13.1174 20.2426 14.2426C19.1174 15.3679 17.5913 16 16 16ZM35.48 16.64C36.7599 15.1987 37.596 13.4181 37.8876 11.5127C38.1792 9.60725 37.9139 7.65815 37.1235 5.9C36.3332 4.14185 35.0516 2.64959 33.4329 1.60285C31.8143 0.5561 29.9276 -0.0005152 28 3.57822e-07C27.4696 3.57822e-07 26.9609 0.210714 26.5858 0.585787C26.2107 0.960859 26 1.46957 26 2C26 2.53043 26.2107 3.03914 26.5858 3.41421C26.9609 3.78929 27.4696 4 28 4C29.5913 4 31.1174 4.63214 32.2426 5.75736C33.3679 6.88258 34 8.4087 34 10C33.9972 11.0505 33.7186 12.0818 33.1921 12.9908C32.6657 13.8999 31.9097 14.6548 31 15.18C30.7035 15.351 30.4558 15.5953 30.2807 15.8895C30.1056 16.1836 30.009 16.5178 30 16.86C29.9916 17.1995 30.0699 17.5356 30.2273 17.8365C30.3848 18.1374 30.6163 18.3933 30.9 18.58L31.68 19.1L31.94 19.24C34.3508 20.3834 36.3846 22.192 37.802 24.4526C39.2193 26.7133 39.9611 29.3319 39.94 32C39.94 32.5304 40.1507 33.0391 40.5258 33.4142C40.9009 33.7893 41.4096 34 41.94 34C42.4704 34 42.9791 33.7893 43.3542 33.4142C43.7293 33.0391 43.94 32.5304 43.94 32C43.9563 28.9309 43.1876 25.9085 41.7069 23.2201C40.2262 20.5317 38.0827 18.2666 35.48 16.64Z\" fill=\"#EB4141\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2 Personas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"material-symbols:resize-rounded\"><path id=\"Vector\" d=\"M3 13V11H5V13H3ZM3 9V7H5V9H3ZM7 5V3H9V5H7ZM11 21V19H13V21H11ZM11 5V3H13V5H11ZM15 21V19H17V21H15ZM19 17V15H21V17H19ZM19 13V11H21V13H19ZM20 9C19.7167 9 19.479 8.904 19.287 8.712C19.095 8.52 18.9993 8.28267 19 8V5H16C15.7167 5 15.479 4.904 15.287 4.712C15.095 4.52 14.9993 4.28267 15 4C15 3.71667 15.096 3.479 15.288 3.287C15.48 3.095 15.7173 2.99934 16 3H19C19.55 3 20.021 3.196 20.413 3.588C20.805 3.98 21.0007 4.45067 21 5V8C21 8.28334 20.904 8.521 20.712 8.713C20.52 8.905 20.2827 9.00067 20 9ZM5 21C4.45 21 3.979 20.804 3.587 20.412C3.195 20.02 2.99934 19.5493 3 19V16C3 15.7167 3.096 15.479 3.288 15.287C3.48 15.095 3.71733 14.9993 4 15C4.28333 15 4.521 15.096 4.713 15.288C4.905 15.48 5.00067 15.7173 5 16V19H8C8.28334 19 8.521 19.096 8.713 19.288C8.905 19.48 9.00067 19.7173 9 20C9 20.2833 8.904 20.521 8.712 20.713C8.52 20.905 8.28267 21.0007 8 21H5ZM19 21V19H21C21 19.55 20.804 20.021 20.412 20.413C20.02 20.805 19.5493 21.0007 19 21ZM3 5C3 4.45 3.196 3.979 3.588 3.587C3.98 3.195 4.45067 2.99934 5 3V5H3Z\" fill=\"#EB4141\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">21 m\u00b2<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7122f795 elementor-widget elementor-widget-text-editor\" data-id=\"7122f795\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Habitaci\u00f3n con cama de matrimonio, Smart TV, escritorio con tel\u00e9fono, caja fuerte, ba\u00f1o privado con ducha ecol\u00f3gica, climatizaci\u00f3n y aislamiento ac\u00fastico, y conexi\u00f3n a Wi-Fi.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-16252c48 e-con-full el-room__buttons e-flex e-con e-child\" data-id=\"16252c48\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-63c3d4e4 e-flex e-con-boxed e-con e-child\" data-id=\"63c3d4e4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37190b45 elementor-widget elementor-widget-heading\" data-id=\"37190b45\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">desde<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6c8999 is-styled-hotel elementor-widget elementor-widget-theme_price\" data-id=\"a6c8999\" data-element_type=\"widget\" data-widget_type=\"theme_price.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <p class=\"pricing-label\">\n        <span class=\"price-eu \">40\u20ac<\/span>\n        <span class=\"price-br hidden\">R$240<\/span>\n    <\/p>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-413c4e2c el-room__button elementor-button-link elementor-widget elementor-widget-button\" data-id=\"413c4e2c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/book.omnibees.com\/hotelresults?CheckIn=&#038;CheckOut=&#038;NRooms=1&#038;ad=1&#038;ag=&#038;ch=0&#038;code=&#038;lang=pt&#038;q=9291\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Seleccionar fechas<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7be29e10 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7be29e10\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-block-end:0;flex-grow:1;border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider--element-align-start .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-start .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-start .elementor-divider__element{margin-inline-start:0}.elementor-widget-divider--element-align-end .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-end .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-end .elementor-divider__element{margin-inline-end:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7428e037 e-con-full el-room e-flex e-con e-child\" data-id=\"7428e037\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9bf44b9 elementor-widget__width-initial el-room__slider elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"9bf44b9\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/1-QuartoCasalPCD-768x512.webp\" alt=\"1-QuartoCasalPCD.webp\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/2-QuartoCasalPCD-768x512.webp\" alt=\"2-QuartoCasalPCD.webp\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/3-QuartoCasalPCD-768x512.webp\" alt=\"3-QuartoCasalPCD.webp\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/4-QuartoCasalPCD-768x512.webp\" alt=\"4-QuartoCasalPCD.webp\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2026\/04\/5-QuartoCasalPCD-768x512.webp\" alt=\"5-QuartoCasalPCD.webp\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18575d27 e-con-full el-room__content e-flex e-con e-child\" data-id=\"18575d27\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-32b14897 e-con-full e-flex e-con e-child\" data-id=\"32b14897\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-409f58cc elementor-widget elementor-widget-heading\" data-id=\"409f58cc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Habitaci\u00f3n Doble PCD<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c8906b6 elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1c8906b6\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M20 3.5H4C3.20435 3.5 2.44129 3.81607 1.87868 4.37868C1.31607 4.94129 1 5.70435 1 6.5V19.5C1 19.7652 1.10536 20.0196 1.29289 20.2071C1.48043 20.3946 1.73478 20.5 2 20.5H6C6.16471 20.4991 6.32665 20.4576 6.47145 20.3791C6.61625 20.3006 6.73941 20.1876 6.83 20.05L8.54 17.5H15.46L17.17 20.05C17.2606 20.1876 17.3838 20.3006 17.5285 20.3791C17.6733 20.4576 17.8353 20.4991 18 20.5H22C22.2652 20.5 22.5196 20.3946 22.7071 20.2071C22.8946 20.0196 23 19.7652 23 19.5V6.5C23 5.70435 22.6839 4.94129 22.1213 4.37868C21.5587 3.81607 20.7956 3.5 20 3.5ZM21 18.5H18.54L16.83 16C16.7454 15.8531 16.6248 15.7302 16.4796 15.6428C16.3344 15.5553 16.1694 15.5062 16 15.5H8C7.83529 15.5009 7.67335 15.5424 7.52855 15.6209C7.38375 15.6994 7.26059 15.8124 7.17 15.95L5.46 18.5H3V13.5H21V18.5ZM7 11.5V10.5C7 10.2348 7.10536 9.98043 7.29289 9.79289C7.48043 9.60536 7.73478 9.5 8 9.5H10C10.2652 9.5 10.5196 9.60536 10.7071 9.79289C10.8946 9.98043 11 10.2348 11 10.5V11.5H7ZM13 11.5V10.5C13 10.2348 13.1054 9.98043 13.2929 9.79289C13.4804 9.60536 13.7348 9.5 14 9.5H16C16.2652 9.5 16.5196 9.60536 16.7071 9.79289C16.8946 9.98043 17 10.2348 17 10.5V11.5H13ZM21 11.5H19V10.5C19 9.70435 18.6839 8.94129 18.1213 8.37868C17.5587 7.81607 16.7956 7.5 16 7.5H14C13.2599 7.50441 12.5476 7.78221 12 8.28C11.4524 7.78221 10.7401 7.50441 10 7.5H8C7.20435 7.5 6.44129 7.81607 5.87868 8.37868C5.31607 8.94129 5 9.70435 5 10.5V11.5H3V6.5C3 6.23478 3.10536 5.98043 3.29289 5.79289C3.48043 5.60536 3.73478 5.5 4 5.5H20C20.2652 5.5 20.5196 5.60536 20.7071 5.79289C20.8946 5.98043 21 6.23478 21 6.5V11.5Z\" fill=\"#EB4141\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1 Cama doble<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"44\" height=\"34\" viewBox=\"0 0 44 34\" fill=\"none\"><path d=\"M22.6 17.44C23.6672 16.5163 24.5231 15.3738 25.1097 14.09C25.6964 12.8063 26 11.4114 26 10C26 7.34784 24.9464 4.8043 23.0711 2.92893C21.1957 1.05357 18.6522 3.57822e-07 16 3.57822e-07C13.3478 3.57822e-07 10.8043 1.05357 8.92893 2.92893C7.05357 4.8043 6 7.34784 6 10C5.99998 11.4114 6.3036 12.8063 6.89025 14.09C7.4769 15.3738 8.33284 16.5163 9.4 17.44C6.60028 18.7078 4.22493 20.7551 2.55796 23.3371C0.89099 25.9191 0.00294371 28.9266 0 32C0 32.5304 0.210714 33.0391 0.585786 33.4142C0.960859 33.7893 1.46957 34 2 34C2.53043 34 3.03914 33.7893 3.41421 33.4142C3.78929 33.0391 4 32.5304 4 32C4 28.8174 5.26428 25.7652 7.51472 23.5147C9.76516 21.2643 12.8174 20 16 20C19.1826 20 22.2348 21.2643 24.4853 23.5147C26.7357 25.7652 28 28.8174 28 32C28 32.5304 28.2107 33.0391 28.5858 33.4142C28.9609 33.7893 29.4696 34 30 34C30.5304 34 31.0391 33.7893 31.4142 33.4142C31.7893 33.0391 32 32.5304 32 32C31.9971 28.9266 31.109 25.9191 29.442 23.3371C27.7751 20.7551 25.3997 18.7078 22.6 17.44ZM16 16C14.8133 16 13.6533 15.6481 12.6666 14.9888C11.6799 14.3295 10.9108 13.3925 10.4567 12.2961C10.0026 11.1997 9.88378 9.99334 10.1153 8.82946C10.3468 7.66557 10.9182 6.59648 11.7574 5.75736C12.5965 4.91824 13.6656 4.3468 14.8295 4.11529C15.9933 3.88378 17.1997 4.0026 18.2961 4.45672C19.3925 4.91085 20.3295 5.67988 20.9888 6.66658C21.6481 7.65327 22 8.81331 22 10C22 11.5913 21.3679 13.1174 20.2426 14.2426C19.1174 15.3679 17.5913 16 16 16ZM35.48 16.64C36.7599 15.1987 37.596 13.4181 37.8876 11.5127C38.1792 9.60725 37.9139 7.65815 37.1235 5.9C36.3332 4.14185 35.0516 2.64959 33.4329 1.60285C31.8143 0.5561 29.9276 -0.0005152 28 3.57822e-07C27.4696 3.57822e-07 26.9609 0.210714 26.5858 0.585787C26.2107 0.960859 26 1.46957 26 2C26 2.53043 26.2107 3.03914 26.5858 3.41421C26.9609 3.78929 27.4696 4 28 4C29.5913 4 31.1174 4.63214 32.2426 5.75736C33.3679 6.88258 34 8.4087 34 10C33.9972 11.0505 33.7186 12.0818 33.1921 12.9908C32.6657 13.8999 31.9097 14.6548 31 15.18C30.7035 15.351 30.4558 15.5953 30.2807 15.8895C30.1056 16.1836 30.009 16.5178 30 16.86C29.9916 17.1995 30.0699 17.5356 30.2273 17.8365C30.3848 18.1374 30.6163 18.3933 30.9 18.58L31.68 19.1L31.94 19.24C34.3508 20.3834 36.3846 22.192 37.802 24.4526C39.2193 26.7133 39.9611 29.3319 39.94 32C39.94 32.5304 40.1507 33.0391 40.5258 33.4142C40.9009 33.7893 41.4096 34 41.94 34C42.4704 34 42.9791 33.7893 43.3542 33.4142C43.7293 33.0391 43.94 32.5304 43.94 32C43.9563 28.9309 43.1876 25.9085 41.7069 23.2201C40.2262 20.5317 38.0827 18.2666 35.48 16.64Z\" fill=\"#EB4141\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2 Personas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"material-symbols:resize-rounded\"><path id=\"Vector\" d=\"M3 13V11H5V13H3ZM3 9V7H5V9H3ZM7 5V3H9V5H7ZM11 21V19H13V21H11ZM11 5V3H13V5H11ZM15 21V19H17V21H15ZM19 17V15H21V17H19ZM19 13V11H21V13H19ZM20 9C19.7167 9 19.479 8.904 19.287 8.712C19.095 8.52 18.9993 8.28267 19 8V5H16C15.7167 5 15.479 4.904 15.287 4.712C15.095 4.52 14.9993 4.28267 15 4C15 3.71667 15.096 3.479 15.288 3.287C15.48 3.095 15.7173 2.99934 16 3H19C19.55 3 20.021 3.196 20.413 3.588C20.805 3.98 21.0007 4.45067 21 5V8C21 8.28334 20.904 8.521 20.712 8.713C20.52 8.905 20.2827 9.00067 20 9ZM5 21C4.45 21 3.979 20.804 3.587 20.412C3.195 20.02 2.99934 19.5493 3 19V16C3 15.7167 3.096 15.479 3.288 15.287C3.48 15.095 3.71733 14.9993 4 15C4.28333 15 4.521 15.096 4.713 15.288C4.905 15.48 5.00067 15.7173 5 16V19H8C8.28334 19 8.521 19.096 8.713 19.288C8.905 19.48 9.00067 19.7173 9 20C9 20.2833 8.904 20.521 8.712 20.713C8.52 20.905 8.28267 21.0007 8 21H5ZM19 21V19H21C21 19.55 20.804 20.021 20.412 20.413C20.02 20.805 19.5493 21.0007 19 21ZM3 5C3 4.45 3.196 3.979 3.588 3.587C3.98 3.195 4.45067 2.99934 5 3V5H3Z\" fill=\"#EB4141\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">23 m\u00b2<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-617a2bfc elementor-widget elementor-widget-text-editor\" data-id=\"617a2bfc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Habitaci\u00f3n adaptada para personas con necesidades especiales, con cama de matrimonio, Smart TV, escritorio con tel\u00e9fono, caja fuerte, ba\u00f1o privado con ducha ecol\u00f3gica, climatizaci\u00f3n, insonorizaci\u00f3n y conexi\u00f3n Wi-Fi.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f22ac4 e-con-full el-room__buttons e-flex e-con e-child\" data-id=\"5f22ac4\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3c6ee1cc e-flex e-con-boxed e-con e-child\" data-id=\"3c6ee1cc\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19d6cf07 elementor-widget elementor-widget-heading\" data-id=\"19d6cf07\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">desde<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-952cf67 is-styled-hotel elementor-widget elementor-widget-theme_price\" data-id=\"952cf67\" data-element_type=\"widget\" data-widget_type=\"theme_price.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <p class=\"pricing-label\">\n        <span class=\"price-eu \">40\u20ac<\/span>\n        <span class=\"price-br hidden\">R$240<\/span>\n    <\/p>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4524d8ca el-room__button elementor-button-link elementor-widget elementor-widget-button\" data-id=\"4524d8ca\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/book.omnibees.com\/hotelresults?CheckIn=&#038;CheckOut=&#038;NRooms=1&#038;ad=1&#038;ag=&#038;ch=0&#038;code=&#038;lang=pt&#038;q=9291\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Seleccionar fechas<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1032d911 e-flex e-con-boxed e-con e-parent\" data-id=\"1032d911\" data-element_type=\"container\" id=\"hotel\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a4bd24f elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"5a4bd24f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hotel<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-607a1fec elementor-widget elementor-widget-theme_hotel_gallery_slider\" data-id=\"607a1fec\" data-element_type=\"widget\" data-widget_type=\"theme_hotel_gallery_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"slider-gallery js-slider-gallery\">\r\n\t\t<div class=\"slider__clip swiper js-swiper\">\r\n\t\t\t<div class=\"slider__slides swiper-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"slider__slide swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider__slide-image-large\">\r\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2025\/04\/Design-sem-nome-2-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"gallery-1\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2025\/04\/Design-sem-nome-2-1.png\" alt=\"\">\r\n\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider__slide-image-small\">\r\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/2-MoovHotelCuritiba.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"gallery-1\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/2-MoovHotelCuritiba.webp\" alt=\"\">\r\n\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider__slide-image-small\">\r\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/3-MoovHotelCuritiba.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"gallery-1\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/3-MoovHotelCuritiba.webp\" alt=\"\">\r\n\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"slider__slide swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider__slide-image-large\">\r\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/4-MoovHotelCuritiba.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"gallery-1\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/4-MoovHotelCuritiba.webp\" alt=\"\">\r\n\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider__slide-image-small\">\r\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/5-MoovHotelCuritiba.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"gallery-1\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/5-MoovHotelCuritiba.webp\" alt=\"\">\r\n\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"slider__slide-image-small\">\r\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/6-MoovHotelCuritiba.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"gallery-1\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/6-MoovHotelCuritiba.webp\" alt=\"\">\r\n\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t<div class=\"swiper-button-prev\"><\/div>\r\n\t\t\t<div class=\"swiper-button-next\"><\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\r\n\t<div class=\"slider-gallery is-mobile js-slider-gallery\">\r\n\t\t<div class=\"slider__clip swiper js-swiper\">\r\n\t\t\t<div class=\"slider__slides swiper-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"slider__slide swiper-slide\">\r\n\t\t\t\t\t\t<div class=\"slider__slide-image-large\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2025\/04\/Design-sem-nome-2-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"gallery-2\">\r\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2025\/04\/Design-sem-nome-2-1.png\" alt=\"\">\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"slider__slide swiper-slide\">\r\n\t\t\t\t\t\t<div class=\"slider__slide-image-large\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/2-MoovHotelCuritiba.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"gallery-2\">\r\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/2-MoovHotelCuritiba.webp\" alt=\"\">\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"slider__slide swiper-slide\">\r\n\t\t\t\t\t\t<div class=\"slider__slide-image-large\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/3-MoovHotelCuritiba.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"gallery-2\">\r\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/3-MoovHotelCuritiba.webp\" alt=\"\">\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"slider__slide swiper-slide\">\r\n\t\t\t\t\t\t<div class=\"slider__slide-image-large\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/4-MoovHotelCuritiba.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"gallery-2\">\r\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/4-MoovHotelCuritiba.webp\" alt=\"\">\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"slider__slide swiper-slide\">\r\n\t\t\t\t\t\t<div class=\"slider__slide-image-large\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/5-MoovHotelCuritiba.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"gallery-2\">\r\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/5-MoovHotelCuritiba.webp\" alt=\"\">\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"slider__slide swiper-slide\">\r\n\t\t\t\t\t\t<div class=\"slider__slide-image-large\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/6-MoovHotelCuritiba.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"gallery-2\">\r\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/6-MoovHotelCuritiba.webp\" alt=\"\">\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t<div class=\"swiper-button-prev\"><\/div>\r\n\t\t\t<div class=\"swiper-button-next\"><\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39d396c4 e-grid e-con-full e-con e-child\" data-id=\"39d396c4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5309c6cc elementor-widget elementor-widget-theme_accordion_widget\" data-id=\"5309c6cc\" data-element_type=\"widget\" data-widget_type=\"theme_accordion_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"accordion js-accordion\">\r\n\t\t\t\t\t<div class=\"accordion__text\">\r\n\t\t\t\t<p><strong>Desayuno buffet<\/strong><br \/>Del\u00e9itese con pan de queso, bacon, huevos revueltos, ensalada de frutas<br \/>y fruta fresca, varios pasteles y boller\u00eda, una selecci\u00f3n de panes, embutidos y quesos, y zumo natural.<\/p>\n\t\t\t<\/div><!-- \/.accordion__text -->\r\n\t\t\r\n\t\t\t\t\t<div class=\"accordion__toggle\">\r\n\t\t\t\t<div class=\"accordion__body\">\r\n\t\t\t\t\t<div class=\"accordion__body-inner\">\r\n\t\t\t\t\t\t<div class=\"accordion__body-entry\">\r\n\t\t\t\t\t\t\t<p>Tambi\u00e9n ofrecemos cereales variados, zumo de naranja natural, fruta fresca en rodajas y distintos tipos de caf\u00e9. Otras opciones veganas y sin gluten disponibles previa petici\u00f3n. <\/p>\n<p>Desayuno abierto a no hu\u00e9spedes. Debe reservarse directamente con nosotros. <\/p>\n<p>Precio a consultar<\/p>\n\t\t\t\t\t\t<\/div><!-- \/.accordion__body-entry -->\r\n\t\t\t\t\t<\/div><!-- \/.accordion__body-inner -->\r\n\t\t\t\t<\/div><!-- \/.accordion__body -->\r\n\r\n\t\t\t\t\t\t\t\t\t<div class=\"accordion__actions\">\r\n\t\t\t\t\t\t<a href=\"#\" class=\"js-accordion-button\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"more-details\">M\u00e1s detalles<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"less-details\">Menos detalles<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div><!-- \/.accordion__actions -->\r\n\t\t\t\t\t\t\t<\/div><!-- \/.accordion__toggle -->\r\n\t\t\t<\/div><!-- \/.accordion -->\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13c2fe0a elementor-widget elementor-widget-theme_accordion_widget\" data-id=\"13c2fe0a\" data-element_type=\"widget\" data-widget_type=\"theme_accordion_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"accordion js-accordion\">\r\n\t\t\t\t\t<div class=\"accordion__text\">\r\n\t\t\t\t<p><strong>Aparcamiento<\/strong><br \/>Disponemos de aparcamiento privado para nuestros hu\u00e9spedes.<\/p>\n<p>Sujeto a disponibilidad.<\/p>\n\t\t\t<\/div><!-- \/.accordion__text -->\r\n\t\t\r\n\t\t\t\t\t<div class=\"accordion__toggle\">\r\n\t\t\t\t<div class=\"accordion__body\">\r\n\t\t\t\t\t<div class=\"accordion__body-inner\">\r\n\t\t\t\t\t\t<div class=\"accordion__body-entry\">\r\n\t\t\t\t\t\t\t<p>Precio: R$ 35,00<\/p>\n\t\t\t\t\t\t<\/div><!-- \/.accordion__body-entry -->\r\n\t\t\t\t\t<\/div><!-- \/.accordion__body-inner -->\r\n\t\t\t\t<\/div><!-- \/.accordion__body -->\r\n\r\n\t\t\t\t\t\t\t\t\t<div class=\"accordion__actions\">\r\n\t\t\t\t\t\t<a href=\"#\" class=\"js-accordion-button\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"more-details\">Precio<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"less-details\">Ver menos<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div><!-- \/.accordion__actions -->\r\n\t\t\t\t\t\t\t<\/div><!-- \/.accordion__toggle -->\r\n\t\t\t<\/div><!-- \/.accordion -->\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73f1ac0c elementor-widget elementor-widget-theme_accordion_widget\" data-id=\"73f1ac0c\" data-element_type=\"widget\" data-widget_type=\"theme_accordion_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"accordion js-accordion\">\r\n\t\t\t\t\t<div class=\"accordion__text\">\r\n\t\t\t\t<p><strong>Recepci\u00f3n 24h<\/strong><br \/>La recepci\u00f3n est\u00e1 abierta las 24 horas y siempre a su disposici\u00f3n.<br \/>Por favor, pague su estancia por adelantado en el check-in.<\/p>\n\t\t\t<\/div><!-- \/.accordion__text -->\r\n\t\t\r\n\t\t\t\t\t<div class=\"accordion__toggle\">\r\n\t\t\t\t<div class=\"accordion__body\">\r\n\t\t\t\t\t<div class=\"accordion__body-inner\">\r\n\t\t\t\t\t\t<div class=\"accordion__body-entry\">\r\n\t\t\t\t\t\t\t<p>Una forma r\u00e1pida y sencilla de hacer el check out.<br \/>S\u00f3lo tiene que dejar su tarjeta en la recepci\u00f3n, en la zona habilitada para ello.<\/p>\n\t\t\t\t\t\t<\/div><!-- \/.accordion__body-entry -->\r\n\t\t\t\t\t<\/div><!-- \/.accordion__body-inner -->\r\n\t\t\t\t<\/div><!-- \/.accordion__body -->\r\n\r\n\t\t\t\t\t\t\t\t\t<div class=\"accordion__actions\">\r\n\t\t\t\t\t\t<a href=\"#\" class=\"js-accordion-button\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"more-details\">Check-out Express<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"less-details\">Menos detalles<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div><!-- \/.accordion__actions -->\r\n\t\t\t\t\t\t\t<\/div><!-- \/.accordion__toggle -->\r\n\t\t\t<\/div><!-- \/.accordion -->\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58983a9e elementor-widget elementor-widget-theme_accordion_widget\" data-id=\"58983a9e\" data-element_type=\"widget\" data-widget_type=\"theme_accordion_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"accordion js-accordion\">\r\n\t\t\t\t\t<div class=\"accordion__text\">\r\n\t\t\t\t<p><strong>Limpieza diaria<\/strong><br \/>Nuestro equipo est\u00e1 siempre atento a sus necesidades y a cada<br \/>detalles de su estancia.<\/p>\n\t\t\t<\/div><!-- \/.accordion__text -->\r\n\t\t\r\n\t\t\t<\/div><!-- \/.accordion -->\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa804d3 e-con-full e-flex e-con e-child\" data-id=\"aa804d3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eeff331 elementor-widget elementor-widget-theme_accordion_widget\" data-id=\"eeff331\" data-element_type=\"widget\" data-widget_type=\"theme_accordion_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"accordion js-accordion\">\r\n\t\t\t\t\t<div class=\"accordion__text\">\r\n\t\t\t\t<p><strong style=\"text-align: var(--text-align);\">Pet-Friendly<\/strong><br \/>Dispomos de comodidades, como camas e ta\u00e7as, para receber os seus amigos de quatro patas. S\u00e3o aceites animais at\u00e9 12kg. <\/p>\n\t\t\t<\/div><!-- \/.accordion__text -->\r\n\t\t\r\n\t\t\t\t\t<div class=\"accordion__toggle\">\r\n\t\t\t\t<div class=\"accordion__body\">\r\n\t\t\t\t\t<div class=\"accordion__body-inner\">\r\n\t\t\t\t\t\t<div class=\"accordion__body-entry\">\r\n\t\t\t\t\t\t\t<p>Debe presentarse el certificado de vacunaci\u00f3n del animal.<\/p>\n<p>Coste adicional previa solicitud.<\/p>\n\t\t\t\t\t\t<\/div><!-- \/.accordion__body-entry -->\r\n\t\t\t\t\t<\/div><!-- \/.accordion__body-inner -->\r\n\t\t\t\t<\/div><!-- \/.accordion__body -->\r\n\r\n\t\t\t\t\t\t\t\t\t<div class=\"accordion__actions\">\r\n\t\t\t\t\t\t<a href=\"#\" class=\"js-accordion-button\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"more-details\">M\u00e1s detalles<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"less-details\">Menos detalles<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div><!-- \/.accordion__actions -->\r\n\t\t\t\t\t\t\t<\/div><!-- \/.accordion__toggle -->\r\n\t\t\t<\/div><!-- \/.accordion -->\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d19ee81 e-con-full e-flex e-con e-child\" data-id=\"7d19ee81\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1bcdc980 elementor-widget elementor-widget-text-editor\" data-id=\"1bcdc980\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Amigos del medio ambiente<\/strong><br \/>Hemos aplicado diversas medidas de sostenibilidad para minimizar nuestro impacto ambiental.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75583934 elementor-widget elementor-widget-button\" data-id=\"75583934\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/hotelmoov.com\/mais-que-um-hotel-uma-experiencia-a-todos-os-niveis\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M14.8297 11.2897L10.5897 7.0497C10.4967 6.95598 10.3861 6.88158 10.2643 6.83081C10.1424 6.78004 10.0117 6.75391 9.8797 6.75391C9.74769 6.75391 9.61698 6.78004 9.49512 6.83081C9.37326 6.88158 9.26266 6.95598 9.1697 7.0497C8.98345 7.23707 8.87891 7.49052 8.87891 7.7547C8.87891 8.01889 8.98345 8.27234 9.1697 8.4597L12.7097 11.9997L9.1697 15.5397C8.98345 15.7271 8.87891 15.9805 8.87891 16.2447C8.87891 16.5089 8.98345 16.7623 9.1697 16.9497C9.26314 17.0424 9.37395 17.1157 9.49579 17.1655C9.61763 17.2152 9.74809 17.2405 9.8797 17.2397C10.0113 17.2405 10.1418 17.2152 10.2636 17.1655C10.3854 17.1157 10.4963 17.0424 10.5897 16.9497L14.8297 12.7097C14.9234 12.6167 14.9978 12.5061 15.0486 12.3843C15.0994 12.2624 15.1255 12.1317 15.1255 11.9997C15.1255 11.8677 15.0994 11.737 15.0486 11.6151C14.9978 11.4933 14.9234 11.3827 14.8297 11.2897Z\" fill=\"#EB4141\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">M\u00e1s informaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3797e5 elementor-widget elementor-widget-theme_accordion_widget\" data-id=\"f3797e5\" data-element_type=\"widget\" data-widget_type=\"theme_accordion_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"accordion js-accordion\">\r\n\t\t\t\t\t<div class=\"accordion__text\">\r\n\t\t\t\t<p><strong>Patio<\/strong><br \/>Disfrute del aire fresco de nuestro patio, donde podr\u00e1 desayunar, relajarse o trabajar<\/p>\n\t\t\t<\/div><!-- \/.accordion__text -->\r\n\t\t\r\n\t\t\t<\/div><!-- \/.accordion -->\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-700c0c30 e-flex e-con-boxed e-con e-parent\" data-id=\"700c0c30\" data-element_type=\"container\" id=\"location\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2007d14e elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"2007d14e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ubicaci\u00f3n<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3288a230 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3288a230\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M20.4604 9.63031C20.32 8.16922 19.8036 6.76939 18.9616 5.56713C18.1195 4.36486 16.9805 3.40114 15.6554 2.7698C14.3303 2.13846 12.8642 1.86103 11.4001 1.96451C9.93592 2.068 8.5235 2.54887 7.30037 3.36031C6.24957 4.06295 5.36742 4.98961 4.71731 6.0737C4.0672 7.15779 3.66526 8.37241 3.54037 9.63031C3.41785 10.88 3.57504 12.1412 4.00054 13.3226C4.42604 14.5039 5.10917 15.5758 6.00037 16.4603L11.3004 21.7703C11.3933 21.864 11.5039 21.9384 11.6258 21.9892C11.7477 22.04 11.8784 22.0661 12.0104 22.0661C12.1424 22.0661 12.2731 22.04 12.3949 21.9892C12.5168 21.9384 12.6274 21.864 12.7204 21.7703L18.0004 16.4603C18.8916 15.5758 19.5747 14.5039 20.0002 13.3226C20.4257 12.1412 20.5829 10.88 20.4604 9.63031ZM16.6004 15.0503L12.0004 19.6503L7.40037 15.0503C6.72246 14.3724 6.20317 13.5526 5.87984 12.6501C5.5565 11.7475 5.43715 10.7845 5.53037 9.83031C5.62419 8.86141 5.93213 7.92547 6.43194 7.09015C6.93175 6.25483 7.61093 5.54102 8.42037 5.00031C9.48131 4.29554 10.7267 3.9196 12.0004 3.9196C13.2741 3.9196 14.5194 4.29554 15.5804 5.00031C16.3874 5.53893 17.065 6.24959 17.5647 7.08125C18.0644 7.9129 18.3737 8.84491 18.4704 9.81031C18.5666 10.7677 18.4488 11.7346 18.1254 12.6409C17.8019 13.5471 17.281 14.3701 16.6004 15.0503ZM12.0004 6.00031C11.1104 6.00031 10.2403 6.26423 9.5003 6.7587C8.76028 7.25316 8.18351 7.95597 7.84291 8.77823C7.50232 9.6005 7.4132 10.5053 7.58684 11.3782C7.76047 12.2511 8.18905 13.053 8.81839 13.6823C9.44773 14.3116 10.2495 14.7402 11.1225 14.9138C11.9954 15.0875 12.9002 14.9984 13.7224 14.6578C14.5447 14.3172 15.2475 13.7404 15.742 13.0004C16.2364 12.2604 16.5004 11.3903 16.5004 10.5003C16.4977 9.30765 16.0228 8.16459 15.1794 7.32125C14.3361 6.4779 13.193 6.00295 12.0004 6.00031ZM12.0004 13.0003C11.5059 13.0003 11.0226 12.8537 10.6114 12.579C10.2003 12.3043 9.87989 11.9138 9.69067 11.457C9.50145 11.0002 9.45194 10.4975 9.54841 10.0126C9.64487 9.52763 9.88297 9.08217 10.2326 8.73254C10.5822 8.38291 11.0277 8.14481 11.5126 8.04835C11.9976 7.95188 12.5003 8.00139 12.9571 8.19061C13.4139 8.37983 13.8043 8.70026 14.079 9.11138C14.3537 9.52251 14.5004 10.0059 14.5004 10.5003C14.5004 11.1634 14.237 11.7992 13.7681 12.2681C13.2993 12.7369 12.6634 13.0003 12.0004 13.0003Z\" fill=\"#EB4141\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Avenida Sete de Setembro, 5732, Batel, Curitiba, CEP 80240-001, Brasil<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11dd2a8 elementor-widget__width-inherit elementor-widget elementor-widget-html\" data-id=\"11dd2a8\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"map map-400\" id=\"contact-page-map\" data-location=\"-25.44720774119209, -49.29324212268389\" data-zoom=\"13\" data-marker6=\"-25.44720774119209, -49.29324212268389, Moov Hotel Curitiba\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-152e2907 e-con-full e-flex e-con e-child\" data-id=\"152e2907\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3699344e e-con-full el-place e-flex e-con e-child\" data-id=\"3699344e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-705fa9f3 el-place__heading elementor-widget elementor-widget-heading\" data-id=\"705fa9f3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Cerca de<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3734eb5a e-con-full el-place__holder e-flex e-con e-child\" data-id=\"3734eb5a\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e978f16 e-con-full e-flex e-con e-child\" data-id=\"e978f16\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d549bd3 elementor-widget elementor-widget-heading\" data-id=\"1d549bd3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Farmacia DrogaVET<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5684f703 elementor-widget elementor-widget-heading\" data-id=\"5684f703\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">180 m<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e88e91 e-con-full e-flex e-con e-child\" data-id=\"6e88e91\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-274c7138 elementor-widget elementor-widget-heading\" data-id=\"274c7138\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Hospital de Santa Cruz<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-387b9408 elementor-widget elementor-widget-heading\" data-id=\"387b9408\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">600 m<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c793c6f e-con-full e-flex e-con e-child\" data-id=\"6c793c6f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a04412a elementor-widget elementor-widget-heading\" data-id=\"2a04412a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Shopping Curitiba<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-138fdd76 elementor-widget elementor-widget-heading\" data-id=\"138fdd76\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">1.8 km<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7af4768 e-con-full e-flex e-con e-child\" data-id=\"7af4768\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2192eb53 elementor-widget elementor-widget-heading\" data-id=\"2192eb53\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">L\u00ednea Turismo<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51cbe040 elementor-widget elementor-widget-heading\" data-id=\"51cbe040\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">3.3 km<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-60dee9c6 e-con-full el-place e-flex e-con e-child\" data-id=\"60dee9c6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47899280 el-place__heading elementor-widget elementor-widget-heading\" data-id=\"47899280\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Principales atracciones<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6677e8c4 e-con-full el-place__holder e-flex e-con e-child\" data-id=\"6677e8c4\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-62d64a3d e-con-full e-flex e-con e-child\" data-id=\"62d64a3d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4600813c elementor-widget elementor-widget-heading\" data-id=\"4600813c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Parque Barigui<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-298a68a elementor-widget elementor-widget-heading\" data-id=\"298a68a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">3,5 km<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79595a7d e-con-full e-flex e-con e-child\" data-id=\"79595a7d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b028503 elementor-widget elementor-widget-heading\" data-id=\"2b028503\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Paseo P\u00fablico<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-721ef602 elementor-widget elementor-widget-heading\" data-id=\"721ef602\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">3.9 km<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a32241e e-con-full e-flex e-con e-child\" data-id=\"3a32241e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a8d217e elementor-widget elementor-widget-heading\" data-id=\"2a8d217e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Jard\u00edn Bot\u00e1nico<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44c031f elementor-widget elementor-widget-heading\" data-id=\"44c031f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">5.1 km<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4692603b e-con-full e-flex e-con e-child\" data-id=\"4692603b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a7aa1b5 elementor-widget elementor-widget-heading\" data-id=\"6a7aa1b5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Museo \u00d3scar Niemeyer <\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-326bc2e2 elementor-widget elementor-widget-heading\" data-id=\"326bc2e2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">5.7 km<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a42f058 e-con-full e-flex e-con e-child\" data-id=\"a42f058\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-205e632 elementor-widget elementor-widget-heading\" data-id=\"205e632\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u00d3pera de Arame<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb683c7 elementor-widget elementor-widget-heading\" data-id=\"bb683c7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">8.6 km<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c4b96bc e-con-full el-place e-flex e-con e-child\" data-id=\"4c4b96bc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-202564f5 el-place__heading elementor-widget elementor-widget-heading\" data-id=\"202564f5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Transporte<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f4fa12 e-con-full el-place__holder e-flex e-con e-child\" data-id=\"5f4fa12\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-356473bb e-con-full e-flex e-con e-child\" data-id=\"356473bb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4264d971 elementor-widget elementor-widget-heading\" data-id=\"4264d971\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Paragem \u00f4nibus\nAv. Sete de Setembro  <\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b178a28 elementor-widget elementor-widget-heading\" data-id=\"2b178a28\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">47 m<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21397894 e-con-full e-flex e-con e-child\" data-id=\"21397894\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4fe5efc4 elementor-widget elementor-widget-heading\" data-id=\"4fe5efc4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">L\u00ednea Turismo<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f35642f elementor-widget elementor-widget-heading\" data-id=\"2f35642f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">3.3 km<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a1687e8 e-con-full e-flex e-con e-child\" data-id=\"6a1687e8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57e5d145 elementor-widget elementor-widget-heading\" data-id=\"57e5d145\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Aeropuerto Afonso Pena<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ab0556e elementor-widget elementor-widget-heading\" data-id=\"2ab0556e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">18.6 km<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a5ada10 e-flex e-con-boxed e-con e-parent\" data-id=\"7a5ada10\" data-element_type=\"container\" id=\"reviews\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4c451301 e-con-full e-flex e-con e-child\" data-id=\"4c451301\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0d3042 elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"f0d3042\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Rese\u00f1as<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23d945c e-con-full e-flex e-con e-child\" data-id=\"23d945c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6a4a879e e-con-full e-flex e-con e-child\" data-id=\"6a4a879e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6fb2a77e elementor-widget-mobile__width-auto elementor-widget elementor-widget-heading\" data-id=\"6fb2a77e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">4.5<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61d53f3 elementor-widget-mobile__width-auto elementor-widget elementor-widget-heading\" data-id=\"61d53f3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Tripadvisor<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-41fc1919 e-con-full e-flex e-con e-child\" data-id=\"41fc1919\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-191396dc elementor-widget elementor-widget-heading\" data-id=\"191396dc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">9.0<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dce93f0 elementor-widget elementor-widget-heading\" data-id=\"6dce93f0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Booking<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-76095b32 e-con-full e-flex e-con e-child\" data-id=\"76095b32\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5e719318 e-con-full e-flex e-con e-child\" data-id=\"5e719318\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4fb8443d e-con-full e-flex e-con e-child\" data-id=\"4fb8443d\" data-element_type=\"container\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:140,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0}\">\n\t\t<div class=\"elementor-element elementor-element-39523610 e-con-full e-flex e-con e-child\" data-id=\"39523610\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3ac265d6 e-con-full e-flex e-con e-child\" data-id=\"3ac265d6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4413aef7 elementor-widget elementor-widget-heading\" data-id=\"4413aef7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Limpieza<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79534ea6 elementor-widget elementor-widget-heading\" data-id=\"79534ea6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">9,4<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ce09e53 elementor-widget elementor-widget-progress\" data-id=\"6ce09e53\" data-element_type=\"widget\" data-widget_type=\"progress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-progress{text-align:start}.elementor-progress-wrapper{position:relative;background-color:#eee;color:#fff;height:100%;border-radius:2px}.elementor-progress-bar{display:flex;background-color:#69727d;width:0;font-size:11px;height:30px;line-height:30px;border-radius:2px;transition:width 1s ease-in-out}.elementor-progress-text{flex-grow:1;white-space:nowrap;text-overflow:ellipsis;overflow:hidden;padding-inline-start:15px}.elementor-progress-percentage{padding-inline-end:15px}.elementor-widget-progress .elementor-progress-wrapper.progress-info .elementor-progress-bar{background-color:#5bc0de}.elementor-widget-progress .elementor-progress-wrapper.progress-success .elementor-progress-bar{background-color:#5cb85c}.elementor-widget-progress .elementor-progress-wrapper.progress-warning .elementor-progress-bar{background-color:#f0ad4e}.elementor-widget-progress .elementor-progress-wrapper.progress-danger .elementor-progress-bar{background-color:#d9534f}.elementor-progress .elementor-title{display:block}@media (max-width:767px){.elementor-progress-text{padding-inline-start:10px}}.e-con-inner .elementor-progress-wrapper,.e-con .elementor-progress-wrapper{height:auto}<\/style>\n\t\t<div class=\"elementor-progress-wrapper progress-info\" role=\"progressbar\" aria-valuemin=\"0\" aria-valuemax=\"100\" aria-valuenow=\"91\">\n\t\t\t<div class=\"elementor-progress-bar\" data-max=\"91\">\n\t\t\t\t<span class=\"elementor-progress-text\"><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-764917e9 e-con-full e-flex e-con e-child\" data-id=\"764917e9\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2333d6aa e-con-full e-flex e-con e-child\" data-id=\"2333d6aa\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ae7668e elementor-widget elementor-widget-heading\" data-id=\"3ae7668e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Ubicaci\u00f3n<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3945ad0b elementor-widget elementor-widget-heading\" data-id=\"3945ad0b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">9,5<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e4c220c elementor-widget elementor-widget-progress\" data-id=\"3e4c220c\" data-element_type=\"widget\" data-widget_type=\"progress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"elementor-progress-wrapper progress-info\" role=\"progressbar\" aria-valuemin=\"0\" aria-valuemax=\"100\" aria-valuenow=\"87\">\n\t\t\t<div class=\"elementor-progress-bar\" data-max=\"87\">\n\t\t\t\t<span class=\"elementor-progress-text\"><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23589d46 e-con-full e-flex e-con e-child\" data-id=\"23589d46\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1eab0f52 e-con-full e-flex e-con e-child\" data-id=\"1eab0f52\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17a7f828 elementor-widget elementor-widget-heading\" data-id=\"17a7f828\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Wi-Fi Gratuito<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4743b4c4 elementor-widget elementor-widget-heading\" data-id=\"4743b4c4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">8,4<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-658dd223 elementor-widget elementor-widget-progress\" data-id=\"658dd223\" data-element_type=\"widget\" data-widget_type=\"progress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"elementor-progress-wrapper progress-info\" role=\"progressbar\" aria-valuemin=\"0\" aria-valuemax=\"100\" aria-valuenow=\"91\">\n\t\t\t<div class=\"elementor-progress-bar\" data-max=\"91\">\n\t\t\t\t<span class=\"elementor-progress-text\"><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa649f7 e-con-full e-flex e-con e-child\" data-id=\"aa649f7\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-63e02889 e-con-full e-flex e-con e-child\" data-id=\"63e02889\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bebdf30 elementor-widget elementor-widget-heading\" data-id=\"7bebdf30\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Calidad-precio<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80720dd elementor-widget elementor-widget-heading\" data-id=\"80720dd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">8,9<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-330c7849 elementor-widget elementor-widget-progress\" data-id=\"330c7849\" data-element_type=\"widget\" data-widget_type=\"progress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"elementor-progress-wrapper progress-info\" role=\"progressbar\" aria-valuemin=\"0\" aria-valuemax=\"100\" aria-valuenow=\"85\">\n\t\t\t<div class=\"elementor-progress-bar\" data-max=\"85\">\n\t\t\t\t<span class=\"elementor-progress-text\"><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7bbaf6b1 e-con-full e-flex e-con e-child\" data-id=\"7bbaf6b1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-559cae0 elementor-widget elementor-widget-theme_reviews_widget\" data-id=\"559cae0\" data-element_type=\"widget\" data-widget_type=\"theme_reviews_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"reviews\">\r\n\t\t\t<div class=\"reviews__inner\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review js-review\" >\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__toggle\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"review__body\">\r\n\t\t\t\t\t\t\t\t\t\t<p>Una estancia estupenda, \u00a1sin duda volver\u00eda!<br \/>La ubicaci\u00f3n es fant\u00e1stica, \u00a1cerca de todo! El desayuno estaba delicioso, con muchas opciones de comida y bebida para todos los gustos.<br \/>No hay ning\u00fan aspecto negativo que destacar.<\/p>\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__body -->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__actions\">\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"js-review-button\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"more-details\">M\u00e1s informaci\u00f3n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"less-details\">Menos informaci\u00f3n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__actions -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__toggle -->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__author\">\r\n\t\t\t\t\t\t\t\t\t\tHugo Pegado\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__author -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__title\">\r\n\t\t\t\t\t\t\t\t\t\t<p><strong>Brasil <\/strong>\u00b7 Booking<\/p>\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__title -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review -->\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"review js-review\" >\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__toggle\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"review__body\">\r\n\t\t\t\t\t\t\t\t\t\t<p>Excelente relaci\u00f3n calidad-precio<br \/>Excelente acogida del personal;<br \/>Habitaci\u00f3n confortable con buen aislamiento ac\u00fastico y confort t\u00e9rmico;<br \/>Excelente ubicaci\u00f3n.<br \/>Nada de lo que quejarse.<\/p>\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__body -->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__actions\">\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"js-review-button\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"more-details\">M\u00e1s informaci\u00f3n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"less-details\">Menos informaci\u00f3n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__actions -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__toggle -->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__author\">\r\n\t\t\t\t\t\t\t\t\t\tDaniel\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__author -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__title\">\r\n\t\t\t\t\t\t\t\t\t\t<p><strong>Brasil <\/strong>\u00b7 Booking<\/p>\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__title -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review -->\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"review js-review\" >\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__toggle\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"review__body\">\r\n\t\t\t\t\t\t\t\t\t\t<p>Un hotel acogedor<br \/>El hotel, como siempre, me sorprende. Ya me hab\u00eda alojado all\u00ed antes, pero esta vez decid\u00ed disfrutarlo al m\u00e1ximo. El desayuno es de primera si decides tomarlo; la habitaci\u00f3n es acogedora y cuenta con secador de pelo. Muy pr\u00e1ctico.<br \/>No hay nada m\u00e1s que a\u00f1adir.<\/p>\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__body -->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__actions\">\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"js-review-button\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"more-details\">M\u00e1s informaci\u00f3n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"less-details\">Menos informaci\u00f3n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__actions -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__toggle -->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__author\">\r\n\t\t\t\t\t\t\t\t\t\tCristiane\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__author -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__title\">\r\n\t\t\t\t\t\t\t\t\t\t<p><strong>Brasil <\/strong>\u00b7 Booking<\/p>\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__title -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review -->\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"review js-review\" >\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__toggle\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"review__body\">\r\n\t\t\t\t\t\t\t\t\t\t<p>Un hotel acogedor<br \/>El hotel, como siempre, me sorprende. Ya me hab\u00eda alojado all\u00ed antes, pero esta vez decid\u00ed disfrutarlo al m\u00e1ximo. El desayuno es de primera si decides tomarlo; la habitaci\u00f3n es acogedora y cuenta con secador de pelo. Muy pr\u00e1ctico.<br \/>No hay nada m\u00e1s que a\u00f1adir.<\/p>\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__body -->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__actions\">\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"js-review-button\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"more-details\">M\u00e1s informaci\u00f3n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"less-details\">Menos informaci\u00f3n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__actions -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__toggle -->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__author\">\r\n\t\t\t\t\t\t\t\t\t\tGeorge\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__author -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__title\">\r\n\t\t\t\t\t\t\t\t\t\t<p><strong>Brasil <\/strong>\u00b7 Booking<\/p>\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__title -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review -->\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"review js-review\" style=\"display: none;\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__toggle\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"review__body\">\r\n\t\t\t\t\t\t\t\t\t\t<p>personal c\u00f3modo y educado<br \/>Tuve una experiencia agradable en el hotel.<br \/>El personal era amable, el desayuno variado y delicioso, la habitaci\u00f3n y el ba\u00f1o limpios, wifi bueno, cama c\u00f3moda, edred\u00f3n c\u00e1lido.<\/p>\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__body -->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__actions\">\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"js-review-button\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"more-details\">M\u00e1s informaci\u00f3n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"less-details\">Menos informaci\u00f3n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__actions -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__toggle -->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__author\">\r\n\t\t\t\t\t\t\t\t\t\tanapaulag0nzalez\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__author -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__title\">\r\n\t\t\t\t\t\t\t\t\t\t<p><strong>S\u00e3o Paulo, SP<\/strong> \u00b7 Tripadvisor<\/p>\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__title -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review -->\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"review js-review\" style=\"display: none;\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__toggle\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"review__body\">\r\n\t\t\t\t\t\t\t\t\t\t<p>\u00a1La mejor elecci\u00f3n! Un hotel incre\u00edble.<br \/>\u00a1Nos encanta! \u00a1La ubicaci\u00f3n y la atenci\u00f3n tan amable nada m\u00e1s llegar!<br \/>Nos quedaremos hasta el lunes... Estamos deseando probar el desayuno...<br \/>\u00a1El hotel est\u00e1 cerca de todo!<br \/>\u00a1Bares, asadores, centros comerciales!<br \/>\u00a1Ha merecido la pena elegirlo! Volveremos siempre que estemos en Curitiba.<\/p>\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__body -->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__actions\">\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"js-review-button\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"more-details\">M\u00e1s informaci\u00f3n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"less-details\">Menos informaci\u00f3n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__actions -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__toggle -->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__author\">\r\n\t\t\t\t\t\t\t\t\t\tJuu\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__author -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__title\">\r\n\t\t\t\t\t\t\t\t\t\t<p><strong>\u00c1guas de Lind\u00f3ia, SP<\/strong> \u00b7 Tripadvisor<\/p>\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__title -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review -->\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"review js-review\" style=\"display: none;\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__toggle\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"review__body\">\r\n\t\t\t\t\t\t\t\t\t\t<p>\u00a1Excelente!<br \/>\u00a1Super\u00f3 mis expectativas! Se lo recomendar\u00e9 a todo mi grupo. \u00a1Relaci\u00f3n calidad-precio! Olor a limpio en todo el hotel.<\/p>\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__body -->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__actions\">\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"js-review-button\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"more-details\">M\u00e1s informaci\u00f3n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"less-details\">Menos informaci\u00f3n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__actions -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__toggle -->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__author\">\r\n\t\t\t\t\t\t\t\t\t\tFABIANO526024\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__author -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__title\">\r\n\t\t\t\t\t\t\t\t\t\t<p><strong>S\u00e3o Lu\u00eds, MA<\/strong> \u00b7 Tripadvisor<\/p>\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__title -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review -->\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"review js-review\" style=\"display: none;\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__toggle\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"review__body\">\r\n\t\t\t\t\t\t\t\t\t\t<p>Gran lugar para alojarse durante un viaje de negocios<br \/>Hotel sin grandes lujos, pero muy eficiente.<br \/>Limpieza impecable, cama muy c\u00f3moda y excelente ubicaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__body -->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__actions\">\r\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"js-review-button\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"more-details\">M\u00e1s informaci\u00f3n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"less-details\">Menos informaci\u00f3n<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__actions -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__toggle -->\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__author\">\r\n\t\t\t\t\t\t\t\t\t\tGabriel D\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__author -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"review__title\">\r\n\t\t\t\t\t\t\t\t\t\t<p>Tripadvisor<\/p>\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review__title -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.review -->\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- \/.reviews__inner -->\r\n\t\t<\/div><!-- \/.reviews -->\r\n\r\n\t\t\t\t\t<div class=\"reviews__actions\">\r\n\t\t\t\t<a href=\"#\" class=\"btn btn--outlined js-expand-all-reviews\">\r\n\t\t\t\t\tLeer m\u00e1s comentarios\t\t\t\t<\/a>\r\n\t\t\t<\/div><!-- \/.reviews__actions -->\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-536070a elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"536070a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0c450a8 e-con-full e-flex e-con e-child\" data-id=\"0c450a8\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4ff0f22 e-con-full e-flex e-con e-child\" data-id=\"4ff0f22\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8dce519 elementor-widget elementor-widget-heading\" data-id=\"8dce519\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfA\u00fan tiene dudas?\nConsulta nuestro chatbot.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-038a878 elementor-widget elementor-widget-text-editor\" data-id=\"038a878\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>El asistente virtual que siempre est\u00e1 ah\u00ed para ti.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-303dc37 elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"303dc37\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/hotelmoov.com\/fr\/contactos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g id=\"Icons\"><path id=\"Vector\" d=\"M17.0008 9H7.00084C6.73563 9 6.48127 9.10536 6.29374 9.29289C6.1062 9.48043 6.00084 9.73478 6.00084 10C6.00084 10.2652 6.1062 10.5196 6.29374 10.7071C6.48127 10.8946 6.73563 11 7.00084 11H17.0008C17.2661 11 17.5204 10.8946 17.708 10.7071C17.8955 10.5196 18.0008 10.2652 18.0008 10C18.0008 9.73478 17.8955 9.48043 17.708 9.29289C17.5204 9.10536 17.2661 9 17.0008 9ZM13.0008 13H7.00084C6.73563 13 6.48127 13.1054 6.29374 13.2929C6.1062 13.4804 6.00084 13.7348 6.00084 14C6.00084 14.2652 6.1062 14.5196 6.29374 14.7071C6.48127 14.8946 6.73563 15 7.00084 15H13.0008C13.2661 15 13.5204 14.8946 13.7079 14.7071C13.8955 14.5196 14.0008 14.2652 14.0008 14C14.0008 13.7348 13.8955 13.4804 13.7079 13.2929C13.5204 13.1054 13.2661 13 13.0008 13ZM12.0008 2C10.6876 2 9.38726 2.25866 8.17401 2.7612C6.96075 3.26375 5.85836 4.00035 4.92977 4.92893C3.05441 6.8043 2.00084 9.34784 2.00084 12C1.9921 14.3091 2.79164 16.5485 4.26084 18.33L2.26084 20.33C2.12208 20.4706 2.02809 20.6492 1.99071 20.8432C1.95334 21.0372 1.97426 21.2379 2.05084 21.42C2.1339 21.5999 2.26855 21.7511 2.43769 21.8544C2.60683 21.9577 2.80284 22.0083 3.00084 22H12.0008C14.653 22 17.1965 20.9464 19.0719 19.0711C20.9473 17.1957 22.0008 14.6522 22.0008 12C22.0008 9.34784 20.9473 6.8043 19.0719 4.92893C17.1965 3.05357 14.653 2 12.0008 2ZM12.0008 20H5.41084L6.34084 19.07C6.52709 18.8826 6.63164 18.6292 6.63164 18.365C6.63164 18.1008 6.52709 17.8474 6.34084 17.66C5.03143 16.352 4.21602 14.6305 4.03353 12.7888C3.85105 10.947 4.31279 9.09901 5.34007 7.55952C6.36735 6.02004 7.89663 4.88436 9.66736 4.34597C11.4381 3.80759 13.3407 3.8998 15.0511 4.60691C16.7614 5.31402 18.1737 6.59227 19.0473 8.22389C19.9209 9.85551 20.2017 11.7395 19.842 13.555C19.4822 15.3705 18.5042 17.005 17.0744 18.1802C15.6446 19.3554 13.8516 19.9985 12.0008 20Z\" fill=\"white\"><\/path><\/g><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hable con nosotros<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36ec780 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"36ec780\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/Chatbot-Moov-1024x683.webp\" class=\"attachment-large size-large wp-image-8129\" alt=\"\" srcset=\"https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/Chatbot-Moov-1024x683.webp 1024w, https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/Chatbot-Moov-300x200.webp 300w, https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/Chatbot-Moov-768x512.webp 768w, https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/Chatbot-Moov-1536x1024.webp 1536w, https:\/\/hotelmoov.com\/wp-content\/uploads\/2024\/01\/Chatbot-Moov.webp 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":12168,"template":"","meta":{"_acf_changed":false},"categories":[],"tags":[],"location":[],"class_list":["post-12163","hotels","type-hotels","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/hotelmoov.com\/es\/wp-json\/wp\/v2\/hotels\/12163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotelmoov.com\/es\/wp-json\/wp\/v2\/hotels"}],"about":[{"href":"https:\/\/hotelmoov.com\/es\/wp-json\/wp\/v2\/types\/hotels"}],"version-history":[{"count":60,"href":"https:\/\/hotelmoov.com\/es\/wp-json\/wp\/v2\/hotels\/12163\/revisions"}],"predecessor-version":[{"id":29512,"href":"https:\/\/hotelmoov.com\/es\/wp-json\/wp\/v2\/hotels\/12163\/revisions\/29512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotelmoov.com\/es\/wp-json\/wp\/v2\/media\/12168"}],"wp:attachment":[{"href":"https:\/\/hotelmoov.com\/es\/wp-json\/wp\/v2\/media?parent=12163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotelmoov.com\/es\/wp-json\/wp\/v2\/categories?post=12163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotelmoov.com\/es\/wp-json\/wp\/v2\/tags?post=12163"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/hotelmoov.com\/es\/wp-json\/wp\/v2\/location?post=12163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}